{"id":46768,"date":"2023-08-11T01:25:37","date_gmt":"2023-08-11T01:25:37","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-08-11T01:25:37","modified_gmt":"2023-08-11T01:25:37","slug":"conversao-de-medida-cautelar-em-acao-de-deposito-pagamento-do-valor-do-bem","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/conversao-de-medida-cautelar-em-acao-de-deposito-pagamento-do-valor-do-bem\/","title":{"rendered":"[MODELO] Convers\u00e3o de Medida Cautelar em A\u00e7\u00e3o de Dep\u00f3sito  &#8211;  Pagamento do Valor do Bem"},"content":{"rendered":"<p>Convers\u00e3o de Medida Cautelar de Busca e Apreens\u00e3o em A\u00e7\u00e3o de Dep\u00f3sito <\/p>\n<\/p>\n<p> Peti\u00e7\u00f5es &#8211; Medidas Cautelares <\/p>\n<p>Frustrou-se a efic\u00e1cia da busca e apreens\u00e3o por n\u00e3o localizar-se o bem. Havendo acordo extrajudicial para pagamento do valor do bem, \u00e9 o pedido para converter-se a a\u00e7\u00e3o de busca e apreens\u00e3o em a\u00e7\u00e3o de dep\u00f3sito. <\/p>\n<\/p>\n<p>EXCELENT\u00cdSSIMO SENHOR DOUTOR JUIZ DE DIREITO DA &#8230;. \u00aa VARA C\u00cdVEL DA COMARCA DE &#8230;.<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.., j\u00e1 qualificada nos Autos de A\u00c7\u00c3O DE BUSCA E APREENS\u00c3O que move contra &#8230;&#8230;&#8230;&#8230;&#8230;.., em curso nesse r. Ju\u00edzo sob o n\u00b0 &#8230;., por seu advogado e procurador adiante assinado, vem, respeitosamente, \u00e0 presen\u00e7a de V. Exa., para expor e requerer o que segue:<\/p>\n<p>I.<\/p>\n<p>Ap\u00f3s, as in\u00fameras dilig\u00eancias realizadas pelo Sr. Oficial de Justi\u00e7a, conforme certificado no feito na tentativa de encontrar o bem buscado, o patrono da Requerente foi procurado pelo filho do Requerido, que, propondo a realiza\u00e7\u00e3o de composi\u00e7\u00e3o amig\u00e1vel para a liquida\u00e7\u00e3o dos valores em atraso, efetuou o pagamento das parcelas vencidas em &#8230;. (portanto duas), do residual, total do plano naquela oportunidade e dos honor\u00e1rios advocat\u00edcios da sucumb\u00eancia, relativos \u00e0 estas parcelas.<\/p>\n<p>Ato cont\u00ednuo, prop\u00f4s a elabora\u00e7\u00e3o de peti\u00e7\u00e3o conjunta de acordo e o parcelamento do restante devido, o que, ao final, acabou n\u00e3o ocorrendo, n\u00e3o tendo o referido senhor efetuado qualquer outro pagamento, ensejando assim o prosseguimento do feito.<\/p>\n<p>II.<\/p>\n<p>Conforme consta da certid\u00e3o exarada pelo Sr. Oficial de Justi\u00e7a, no verso do r. mandado de Busca e Apreens\u00e3o, embora tivesse se dirigido in\u00fameras vezes no endere\u00e7o do Requerido, n\u00e3o conseguiu cumprir integralmente o r. Mandado de Busca e Apreens\u00e3o, em raz\u00e3o do bem objeto da presente a\u00e7\u00e3o n\u00e3o mais se encontrar na posse do Requerido, conforme declara\u00e7\u00e3o prestada pelo mesmo ao Sr. &#8230;.<\/p>\n<p>III.<\/p>\n<p>Por outro lado como prev\u00ea o contrato de Aliena\u00e7\u00e3o Fiduci\u00e1ria acostado aos Autos, o Requerido mant\u00e9m a posse do ve\u00edculo adquirido, atrav\u00e9s plano de cons\u00f3rcio do requerente, \u00e0 titulo prec\u00e1rio (cl\u00e1usula 5\u00aa), a qual pela falta de pagamento evidenciada, tornou-se ileg\u00edtima (cl\u00e1usula 6\u00aa), dando assim o direito \u00e0 Requerente de exigi-la (a posse) de pronto.<\/p>\n<p>IV.<\/p>\n<p>Assim e conforme pactuado no Contrato acostado \u00e0 inaugural, tendo assumido as obriga\u00e7\u00f5es de Deposit\u00e1rio do bem ora buscado, e n\u00e3o dando ao Sr. &#8230;. qualquer informa\u00e7\u00e3o quanto o seu paradeiro, deve o Requerido, responder \u00e0s penas de lei para os casos de infidelidade deposit\u00e1ria.<\/p>\n<p>V.<\/p>\n<p>Diante do exposto, requer-se \u00e0 V.Exa. a convers\u00e3o da presente em A\u00e7\u00e3o de Dep\u00f3sito, posto que atendidas todas as formalidades legais (art. 902 do CPC), requerendo, para tanto, a cita\u00e7\u00e3o do Requerido para que no prazo legal, entregue o bem em ju\u00edzo, ou consigne o equivalente em dinheiro, valor atualizado do d\u00e9bito R$ &#8230;. (&#8230;.), sob pena de n\u00e3o o fazendo, por economia e brevidade processual, ser-lhe decretada a pris\u00e3o at\u00e9 um ano (par\u00e1grafo 1\u00ba Art. 902, C.P.C.), na conformidade do Par\u00e1grafo \u00fanico do Art. 904, do mesmo Codex.<\/p>\n<p>Outrossim, e pela mesma via, cumprida a medida deferida, seja o Requerido citado para, ap\u00f3s a entrega do bem ou o pagamento valor correspondente, em Ju\u00edzo, querendo, conteste a presente a\u00e7\u00e3o, tudo na conformidade dos dispositivos legais reguladores da mat\u00e9ria.<\/p>\n<p>Termos em que,<\/p>\n<p>Pede deferimento.<\/p>\n<p>&#8230;., &#8230;. de &#8230;. de &#8230;.<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;<\/p>\n<p>Advogado OAB\/&#8230; <\/p><\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[528],"class_list":["post-46768","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-kit-peticoes-diversas"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/46768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=46768"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=46768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}