{"id":37814,"date":"2023-08-04T19:29:37","date_gmt":"2023-08-04T19:29:37","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-08-04T19:29:37","modified_gmt":"2023-08-04T19:29:37","slug":"agravo-de-instrumento-transcricao-integral-de-acordaos-nao-e-indispensavel-para-demonstrar-divergencia-jurisprudencial","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/agravo-de-instrumento-transcricao-integral-de-acordaos-nao-e-indispensavel-para-demonstrar-divergencia-jurisprudencial\/","title":{"rendered":"[MODELO] Agravo de Instrumento  &#8211;  Transcri\u00e7\u00e3o integral de ac\u00f3rd\u00e3os n\u00e3o \u00e9 indispens\u00e1vel para demonstrar diverg\u00eancia jurisprudencial"},"content":{"rendered":"<p>Agravo de Instrumento Contra Decis\u00e3o que Negou Seguimento a Recurso Especial <\/p>\n<\/p>\n<p> Peti\u00e7\u00f5es &#8211; Pe\u00e7as Criminais <\/p>\n<p>Recurso proposto face a decis\u00e3o que negou seguimento ao recurso especial criminal com base na inexist\u00eancia de transcri\u00e7\u00e3o integral de ac\u00f3rd\u00e3os que demonstrem a diverg\u00eancia jurisprudencial havida. <\/p>\n<\/p>\n<p>EXCELENT\u00cdSSIMO SENHOR DOUTOR PRESIDENTE DO TRIBUNAL DA AL\u00c7ADA DO ESTADO DO &#8230;.<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.., nos presentes autos de Recurso Especial Criminal n\u00ba &#8230;., em face da decis\u00e3o de fls. &#8230;. e &#8230;., vem, respeitosamente, \u00e0 presen\u00e7a de Vossa Excel\u00eancia, apresentar<\/p>\n<p>AGRAVO DE INSTRUMENTO<\/p>\n<p>Fazendo-o com esteio no art. 522 e seguintes do C\u00f3digo de Processo Civil e demais dispositivos aplic\u00e1veis, pelos aspectos f\u00e1ticos e jur\u00eddicos que em apartado passa a expor:<\/p>\n<p>&quot;Ex positis&quot;, requer seja reformada a decis\u00e3o agravada na oportunidade do ju\u00edzo da retrata\u00e7\u00e3o, em assim n\u00e3o ocorrendo, ap\u00f3s as formalidades de estilo, requer seja julgado o presente recurso ao tribunal ad quem.<\/p>\n<p>Nestes termos<\/p>\n<p>Pede deferimento.<\/p>\n<p>&#8230;., &#8230;. de &#8230;. de &#8230;.<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; <\/p>\n<p>Advogado<\/p>\n<p>RAZ\u00d5ES DE RECURSO DE AGRAVO DE INSTRUMENTO<\/p>\n<p>Agravante: &#8230;.<\/p>\n<p>APELA\u00c7\u00c3O CRIMINAL N\u00ba &#8230;., da &#8230;. Vara Criminal de &#8230;.<\/p>\n<p>A decis\u00e3o agravada nega seguimento ao recurso com base na inexist\u00eancia de transcri\u00e7\u00e3o integral de ac\u00f3rd\u00e3os que demonstrem a diverg\u00eancia jurisprudencial havida.<\/p>\n<p>Ocorre, por\u00e9m, que o translado das ementas dos referidos ac\u00f3rd\u00e3os, por si s\u00f3, j\u00e1 caracteriza a diverg\u00eancia como exigida, dispensando assim a transcri\u00e7\u00e3o na \u00edntegra dos ac\u00f3rd\u00e3os, o que seria em demasiado formalista e n\u00e3o alteraria a ess\u00eancia de tal demonstra\u00e7\u00e3o, conseguindo-se, desta forma, alcan\u00e7ar o objetivo desejado.<\/p>\n<p>As ementas citadas cumpriram com o seu objetivo de demonstrar diverg\u00eancia jurisprudencial, visto que estas reproduziram fiel e inequivocamente os seus respectivos ac\u00f3rd\u00e3os em seus conte\u00fados fundamentais. Sen\u00e3o vejamos:<\/p>\n<p>Neste sentido, tem-se o pensamento de SAMUEL MONTEIRO:<\/p>\n<p>&quot;Todavia, al\u00e9m da decis\u00e3o s\u00e1bia, contr\u00e1ria a esse formalismo, cabe aqui ponderar que: b) outras vezes, do paradigma s\u00f3 \u00e9 relevante a pr\u00f3pria ementa, quando traduz com precis\u00e3o o tema relevante do ac\u00f3rd\u00e3o; c) dentro desse contexto, que interesse h\u00e1 em obrigar-se o recorrente a longas infrut\u00edferas transcri\u00e7\u00f5es de trechos do ac\u00f3rd\u00e3o paradigma, se dele aproveita-se apenas a ementa? d) ademais, se o paradigma \u00e9 reproduzido no reposit\u00f3rio oficial ou no reposit\u00f3rio autorizado, e a ementa do paradigma satisfaz o teor fundamental do ac\u00f3rd\u00e3o, j\u00e1 n\u00e3o est\u00e1 na hora de se abandonar o formalismo burocr\u00e1tico exagerado que poda e tolhe a garantia constitucional do acesso ao STJ?&quot; (RECURSO ESPECIAL E EXTRAORDIN\u00c1RIO, 1\u00aa ed., Hemus Editora Limitada, 1992).<\/p>\n<p>Portanto, deve-se ter em mente o objetivo maior do recurso especial que \u00e9 o de assegurar o cumprimento de um direito constitucional, para que atrav\u00e9s de uma an\u00e1lise mais profunda de uma determinada quest\u00e3o seja poss\u00edvel chegar a uma verdadeira Justi\u00e7a.<\/p>\n<p>Assim, a recorrente, mesmo n\u00e3o tendo reproduzido os ac\u00f3rd\u00e3os na \u00edntegra, n\u00e3o pode ter seu direito cerceado mais uma vez, mesmo porque, n\u00e3o se fugiu ao sentido real do recurso especial.<\/p>\n<p>Em face das raz\u00f5es delineadas, comprovado restou que a decis\u00e3o agravada deve ser integralmente reformada, dando-se provimento total ao recurso especial em tela.<\/p>\n<p>Nestes termos,<\/p>\n<p>Pede deferimento.<\/p>\n<p>&#8230;., &#8230;. de &#8230;. de &#8230;.<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.<\/p>\n<p>Advogado OAB\/&#8230; <\/p><\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[528],"class_list":["post-37814","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-kit-peticoes-diversas"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/37814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=37814"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=37814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}