{"id":3085271,"date":"2024-06-08T11:23:54","date_gmt":"2024-06-08T11:23:54","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2024-06-08T11:23:54","modified_gmt":"2024-06-08T11:23:54","slug":"pedido-de-alvara-judicial-heranca-e-fgts","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/pedido-de-alvara-judicial-heranca-e-fgts\/","title":{"rendered":"[MODELO] Pedido de Alvar\u00e1 Judicial  &#8211;  Heran\u00e7a e FGTS"},"content":{"rendered":"<p><strong>EXCELENT\u00cdSSIMO SENHOR JUIZ DE DIREITO DA_________\u00aa VARA DE FAM\u00cdLIA E SUCESS\u00d5ES DA COMARCA\/SIGLA ESTADO<\/strong><\/p>\n<p><\/p>\n<p><strong>(REQUERENTE)<\/strong>, brasileiro, casado, comerciante, inscrito no CPF sob o n\u00ba xxx e no RG sob o n\u00ba xxx, com endere\u00e7o eletr\u00f4nico&#8230;, residente e domiciliado na Rua, casa n\u00ba XX, Bairro xxx, CEP xxx, ;<strong>(REQUERENTE 2)<\/strong>, brasileiro, solteiro, auxiliar de cozinha, inscrito no CPF sob o n\u00ba xxx, portador da c\u00e9dula de identidade xxx, com endere\u00e7o eletr\u00f4nico&#8230;, residente e domiciliado na cidade de CIDADE-UF; <strong>(REQUERENTE)<\/strong>, brasileiro, solteiro, estudante, inscrito no CPF sob o n\u00ba xxx ,portador da c\u00e9dula de identidade xxx, com endere\u00e7o eletr\u00f4nico&#8230;, residente e domiciliado na cidade de CIDADE-UF, por seu advogado infra-assinado (doc. 01), com escrit\u00f3rio situado nesta cidade, na rua ___________, n\u00b0 ___, bairro __________ ,nesta cidade de __________, onde recebe intima\u00e7\u00f5es e avisos, vem \u00e0 presen\u00e7a de Vossa Excel\u00eancia requerer a expedi\u00e7\u00e3o de<\/p>\n<p><strong>              ALVAR\u00c1 JUDICIAL<\/strong><\/p>\n<p>Pelas raz\u00f5es de fato e de Direito que passam a expor.<\/p>\n<p>No dia 15\/12\/2009, faleceu o Sr. xxx, empregado p\u00fablico federal aposentado, inscrito no RG sob o n\u00ba ZZZZZZZZZ e no CPF sob o n\u00ba xxx, <strong>pai dos Requerentes<\/strong>, consoante c\u00f3pia da Certid\u00e3o de \u00d3bito em anexo. <\/p>\n<p>O falecido n\u00e3o tinha outros filhos e era separado judicialmente da Sr\u00aa xxx, m\u00e3e dos Requerentes, falecida em 30\/03\/1998. Assim, forte na legisla\u00e7\u00e3o vigente, os Requerentes, todos maiores de idade, s\u00e3o os \u00fanicos herdeiros\/sucessores do falecido Sr. xxx, consoante tamb\u00e9m faz prova a Certid\u00e3o de Inexist\u00eancia de dependentes habilitados \u00e0 pens\u00e3o por morte junto ao INSS.<\/p>\n<\/p>\n<p>Ocorre que o finado pai dos Requerentes, no ano de 2008, havia ajuizado a\u00e7\u00e3o judicial em face da Uni\u00e3o, junto ao Juizado Especial Federal da Comarca de Porto Alegre, a qual foi autuada sob o n\u00ba. XXXXXXXXXXXe em 10\/07\/2009, teve certificado o tr\u00e2nsito em julgado da decis\u00e3o de proced\u00eancia.<\/p>\n<p>A Uni\u00e3o, em aten\u00e7\u00e3o a condena\u00e7\u00e3o que lhe foi imposta, efetuou em setembro de 2009 o <strong>dep\u00f3sito do valor na conta n\u00ba XXXXXXXXX, ag\u00eancia XXX, da Caixa Econ\u00f4mica Federal<\/strong>, conforme comprovante anexado.<\/p>\n<p>Contudo, ante o agravamento da mol\u00e9stia, j\u00e1 naquela \u00e9poca o <em>De Cujus <\/em>se encontrava em interna\u00e7\u00e3o hospitalar, sem condi\u00e7\u00f5es de locomo\u00e7\u00e3o, vindo a falecer sem conseguir sacar o montante que lhe foi deferido.<\/p>\n<p>Al\u00e9m deste valor, na mesma institui\u00e7\u00e3o banc\u00e1ria, tamb\u00e9m h\u00e1 depositado valor na conta de FGTS do falecido, oriundo principalmente da restitui\u00e7\u00e3o da Lei Complementar 110\/2001, que em 07\/01\/2010 alcan\u00e7ava o montante de R$ 12.701,30 (doze mil e setecentos e um Reais e trinta centavos), conforme correspond\u00eancia encaminhada pela Caixa Econ\u00f4mica Federal, em anexo.<\/p>\n<p>Destarte, tendo em vista que o <em>De Cujus<\/em> deixou algumas d\u00edvidas e outras foram adquiridas em raz\u00e3o de seu tratamento de sa\u00fade e cerim\u00f4nias f\u00fanebres, bem como serem os Requerentes todos maiores de idade e \u00fanicos herdeiros, vem a este MM. Ju\u00edzo requerer a expedi\u00e7\u00e3o de alvar\u00e1 para levantamento dos valores destinados ao Sr. ZZZZZZZZZZZZ, constantes em conta(s) banc\u00e1ria(s) junto \u00e0 Caixa Econ\u00f4mica Federal. <\/p>\n<p>Por fim, requerem a concess\u00e3o do benef\u00edcio da Assist\u00eancia Judici\u00e1ria Gratuita, por serem pessoas pobres nos termos da lei e protestam pela produ\u00e7\u00e3o de todas as provas admitidas em direito, em especial prova documental e testemunhal que se fizerem necess\u00e1rias.<\/p>\n<p>Atribuem \u00e0 causa o valor de R$ 15.737,61 para fins de distribui\u00e7\u00e3o.<\/p>\n<p>Nestes termos,<\/p>\n<p>Pedem e esperam deferimento.<\/p>\n<p>CIDADE-UF, ____ de ___________ de 20XX.<\/p>\n<p>XXXXXXXXXXX<\/p>\n<p>OAB\/XX XX.XXX<\/p>\n<p>__________________<\/p>\n<p>ROL DE DOCUMENTOS ANEXOS:<\/p>\n<p>1- Instrumentos de mandato;<\/p>\n<p>2- Certid\u00e3o de \u00f3bito do Sr. Paulo;<\/p>\n<p>3- Certid\u00e3o de Casamento e separa\u00e7\u00e3o judicial do Sr. _______;<\/p>\n<p>4- Certid\u00e3o de \u00f3bito da Sr\u00aa ________;<\/p>\n<p>5- Certid\u00e3o de Inexist\u00eancia de Dependentes Habilitados \u00e0 Pens\u00e3o por Morte junto ao INSS;<\/p>\n<p>6- Refer\u00eancias do processo 2008.71.52.XXXXXX-8<strong>.<\/strong><\/p>\n<p>7- Of\u00edcio da Caixa Econ\u00f4mica Federal sobre dep\u00f3sito de FGTS relativo \u00e0 Lei Complementar 110\/2001.<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[156],"class_list":["post-3085271","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-trabalhista"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/3085271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=3085271"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=3085271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}