{"id":3054806,"date":"2024-06-08T04:55:02","date_gmt":"2024-06-08T04:55:02","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2024-06-08T04:55:02","modified_gmt":"2024-06-08T04:55:02","slug":"revogacao-prisao-por-portar-arma-numero-raspado","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/revogacao-prisao-por-portar-arma-numero-raspado\/","title":{"rendered":"[MODELO] Revoga\u00e7\u00e3o Pris\u00e3o por Portar Arma N\u00famero Raspado"},"content":{"rendered":"<p>Requerimento de Liberdade Provis\u00f3ria, no qual \u00e9 pleiteado o livramento do custodiado sob invoca\u00e7\u00e3o da desnecessidade da medida constritiva. O requerimento fundamentou-se na excepcionalidade da pris\u00e3o preventiva e na alega\u00e7\u00e3o de n\u00e3o haver veda\u00e7\u00e3o para a concess\u00e3o de liberdade provis\u00f3ria em fun\u00e7\u00e3o do delito cometido.<\/p>\n<p>===================================================<\/p>\n<p><strong>2\u00aa. Vara Criminal da Zona Norte de Natal<\/strong><\/p>\n<p><strong>Auto de Pris\u00e3o em Flagrante<\/strong><\/p>\n<p><strong>Proced. n\u00ba.: (XXX)<\/strong><\/p>\n<p><strong>Requerimento de Liberdade Provis\u00f3ria<\/strong><\/p>\n<p><strong>Requerente: (XXX)<\/strong><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong>MM\u00aa. Ju\u00edza<\/strong>:<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Trata-se de reitera\u00e7\u00e3o de requerimento de liberdade provis\u00f3ria formulado em favor de (XXX), sob o qual recaem suspeitas da pr\u00e1tica do delito previsto no art. 16, IV da Lei 10.826\/03, segundo a autoridade policial, sob invoca\u00e7\u00e3o da desnecessidade da medida constritiva.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0A pris\u00e3o cautelar, consoante entendimento pac\u00edfico, \u00e9 medida excepcional, <em>in extremis<\/em>. A liberdade do cidad\u00e3o, ao responder o processo, \u00e9 a regra.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Por outro lado, a pr\u00f3pria Carta Magna e a legisla\u00e7\u00e3o de integra\u00e7\u00e3o, enunciam exce\u00e7\u00f5es, com a finalidade maior de resguardar a paz social e jur\u00eddica, cerceando, ainda que temporariamente, a liberdade dos acusados (manuten\u00e7\u00e3o da ordem p\u00fablica ou econ\u00f4mica, conveni\u00eancia da instru\u00e7\u00e3o criminal, aplica\u00e7\u00e3o da lei penal).<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0O motivo da medida constritiva \u00e9 sempre a verifica\u00e7\u00e3o de sua necessidade. Ou esta se encontra e permanece presente, ou n\u00e3o h\u00e1 falar-se em pris\u00e3o, mas livramento.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Em rela\u00e7\u00e3o ao assunto, ensina TOURINHO FILHO:<\/p>\n<p><em>&quot;J\u00e1 vimos que a pris\u00e3o preventiva \u00e9 medida excepcional e, por isso mesmo, decret\u00e1vel em casos de extrema necessidade. Segue-se, pois, que, se durante o processo o Juiz constatar que o motivo ou os motivos que a ditaram j\u00e1 n\u00e3o mais subsistem, poder\u00e1 revog\u00e1-la. \u00c9 claro que, se a medida excepcional fica condicionada a uma daquelas circunst\u00e2ncias &#8211; garantir a ordem p\u00fablica, preservar a instru\u00e7\u00e3o criminal e assegurar a aplica\u00e7\u00e3o da lei penal -, se nenhum desses motivos subsiste, outro caminho n\u00e3o resta ao Juiz sen\u00e3o revogar a medida odiosa. Cumpre observar que, atualmente, a pris\u00e3o provis\u00f3ria, entre n\u00f3s, fica adstrita a uma daquelas circunst\u00e2ncias.<\/em><strong><em> Nem mesmo a pris\u00e3o em flagrante, seja a infra\u00e7\u00e3o afian\u00e7\u00e1vel ou inafian\u00e7\u00e1vel, pode subsistir, se n\u00e3o houver a necessidade de encarceramento, expressa naquela f\u00f3rmula do art. 312 do CPP.<\/em><\/strong><em> Por outro lado, mesmo revogada a preventiva, tal como previsto no art. 316 do CPP, nada impede que o Juiz, de of\u00edcio ou a requerimento do Minist\u00e9rio P\u00fablico ou do querelante, venha a redecret\u00e1-la. Em que hip\u00f3tese? Se sobrevierem as raz\u00f5es que a justifiquem.&quot; (TOURINHO FILHO, Fernando da Costa. Processo Penal. Vol. 3, 18\u00aa. Ed., rev. e atual., S\u00e3o Paulo, Saraiva, 10000007, p. 487, negrito nossos).<\/em><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0No caso concreto, antes e ap\u00f3s os pronunciamentos da Presentante do Minist\u00e9rio P\u00fablico e do Juiz Plantonistas no primeiro pleito, foram carreados documentos comprobat\u00f3rios de qualifica\u00e7\u00e3o do conduzido, certid\u00e3o negativa de feitos criminais, v\u00e1rias declara\u00e7\u00f5es assinadas por pessoas que alegam conhecer o requerente e atestando-lhe bom comportamento, atividades habituais em estudo e emprego e decis\u00f5es judiciais no sentido pretendido. <\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Com todo o merecido respeito aos eminentes parecer e decis\u00e3o proferidos, entendo que os fatos ora mencionados, que instruem o pedido, aliados \u00e0 n\u00e3o extra\u00e7\u00e3o de outros, concretos, no auto de pris\u00e3o em flagrante, que evidenciem raz\u00f5es de prote\u00e7\u00e3o \u00e0 sociedade, com a segrega\u00e7\u00e3o do conduzido, deve orientar no sentido da concess\u00e3o do pleito.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0O requerente n\u00e3o responde processos penais, est\u00e1 identificado, reside no distrito da culpa com estabilidade, n\u00e3o havendo raz\u00f5es para crer em prov\u00e1vel fuga ou perturba\u00e7\u00e3o da instru\u00e7\u00e3o criminal. Demais disso, entendo, com as devidas v\u00eanias aos posicionamentos contr\u00e1rios, que o fato de ter sido o requerente autuado em flagrante por portar uma arma de fogo com a numera\u00e7\u00e3o raspada n\u00e3o o torna, de imediato, uma amea\u00e7a \u00e0 sociedade, tampouco revela, <em>per se<\/em>, periculosidade (o que poderia ocorrer com a confronta\u00e7\u00e3o de antecedentes), que justificariam a constri\u00e7\u00e3o de sua liberdade, para assegurar a ordem p\u00fablica. Os depoimentos revelam que a arma de fogo estava dentro de uma bolsa pequena que carregava, n\u00e3o tendo sido sequer empregada com a sua mostra, muito menos acionada, ainda que em via p\u00fablica, sem destinat\u00e1rio certo. O abalo \u00e0 ordem p\u00fablica, genericamente, sempre ocorre com a pr\u00e1tica de um delito, seja ele de pequeno, m\u00e9dio, ou grande potencial ofensivo. Por\u00e9m, para os fins processuais de supress\u00e3o da liberdade para assegur\u00e1-la do perigo, deve ser demonstrado, sempre concretamente, inviabilizando prov\u00e1veis reitera\u00e7\u00f5es de crimes, apenas como exemplo. \u00c9 a exig\u00eancia da necessidade da medida acautelat\u00f3ria. <\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Poder-se-ia invocar, contrariamente, que a Lei 10.826\/2003, em seu art. 21, diz que os crimes nela previstos nos arts. 16, 17 e 18 s\u00e3o insuscet\u00edveis de liberdade provis\u00f3ria, o que tornaria juridicamente imposs\u00edvel o pedido. Especificamente sobre essa veda\u00e7\u00e3o prevista no &quot;Estatuto do Desarmamento&quot;, al\u00e9m de mencionar algumas normas constitucionais processuais de garantia, escreve Paulo Rangel:<\/p>\n<p>&quot;Vamos imaginar um exemplo:<\/p>\n<p><em>O indiv\u00edduo, claro nosso famoso T\u00edcio, \u00e9 preso e autuado em flagrante delito na delegacia, por violar o art. 14, sem registro da arma, e \u00e9 recolhido ao c\u00e1rcere (o crime \u00e9 inafian\u00e7\u00e1vel). Contudo, poder\u00e1 o juiz conceder liberdade provis\u00f3ria, nos exatos limites do par\u00e1grafo \u00fanico do art. 310 do CPP, j\u00e1 que a veda\u00e7\u00e3o de liberdade provis\u00f3ria \u00e9 para os crimes dos arts. 16, 17 e 18 e <\/em><strong><em>N\u00c3OPARA O CRIME DO ART. 14<\/em><\/strong><em>, o que, por si s\u00f3, nos autoriza outra discuss\u00e3o (ao proibir a liberdade provis\u00f3ria para esses crimes o legislador restabelece a pris\u00e3o obrigat\u00f3ria no processo penal o que caracteriza um retrocesso social inadmiss\u00edvel em um Estado Democr\u00e1tico de Direito. Tal veda\u00e7\u00e3o \u00e9 inconstitucional, pois n\u00e3o se retrocede diante das conquistas sociais alcan\u00e7adas, pelo menos enquanto estivermos na democracia) (..)&quot; (RANGEL, Paulo. Direito Processual Penal. 10\u00aa. ed., 2\u00aa. tir., rev., ampl. e atual., Rio de Janeiro: Lumen Juris, 2012, p. 704) (destaque do autor). <\/em><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Poder\u00edamos invocar, demais disso, v\u00e1rias normas-princ\u00edpio da Constitui\u00e7\u00e3o Federal para repelir a constitucionalidade do referido art. 21: a. O princ\u00edpio da razoabilidade; b. O da proporcionalidade, que \u00e9 inerente ao devido processo legal (exigindo necessidade, idoneidade\/adequa\u00e7\u00e3o da medida e proporcionalidade em sentido estrito); c. O da reserva de Justi\u00e7a; d. O da motiva\u00e7\u00e3o das decis\u00f5es judiciais (que n\u00e3o se conforma com a cita\u00e7\u00e3o do m\u00f3vel legal) etc.. Para cada um deles haveria uma extensa justifica\u00e7\u00e3o cient\u00edfica. Entendo-as inoportunas e desnecess\u00e1rias. O requerente n\u00e3o quer saber as raz\u00f5es da concess\u00e3o de seu pedido, pois almeja alcan\u00e7ar a liberdade, ainda que vinculada processualmente. Fica a discuss\u00e3o para o plano acad\u00eamico ou, o que evidentemente n\u00e3o espera este \u00d3rg\u00e3o Ministerial, para eventual rem\u00e9dio constitucional.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Todo Juiz no Brasil, em face do controle difuso, pode verificar a compatibilidade vertical de textos de normas infraconstitucionais aos preceitos da Constitui\u00e7\u00e3o Federal, negando efic\u00e1cia \u00e0queles que entender que violam a hierarquia do ordenamento jur\u00eddico. Assim, no caso em an\u00e1lise, declarando incidentalmente a inconstitucionalidade do art. 21 do Estatuto do Desarmamento, aplica as normas pertinentes ao C\u00f3digo de Processo Penal. <\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0O Superior Tribunal de Justi\u00e7a vem trilhando em igual sentido, com especial \u00eanfase no argumento da motiva\u00e7\u00e3o das decis\u00f5es judiciais. Com efeito, podemos citar os seguintes ac\u00f3rd\u00e3os:<\/p>\n<p>&quot;Ementa: CRIMINAL. RESP. ART. 16, PAR\u00c1GRAFO \u00daNICO, IV, DA LEI 10.826\/03. <strong>LIBERDADE PROVIS\u00d3RIA. VEDA\u00c7\u00c3O DO ART. 21 DO ESTATUTO DO DESARMAMENTO.<\/strong> <strong>GRAVIDADE DO DELITO<\/strong>. <strong>AUS\u00caNCIA DE CONCRETA FUNDAMENTA\u00c7\u00c3O.<\/strong> CIRCUNST\u00c2NCIAS SUBSUMIDAS NO TIPO PENAL. <strong>NECESSIDADE DA CUST\u00d3DIA N\u00c3O DEMONSTRADA.<\/strong> PRESEN\u00c7A DE CONDI\u00c7\u00d5ES PESSOAIS FAVOR\u00c1VEIS. RECURSO DESPROVIDO.<br \/>I. Hip\u00f3tese em que o recorrido foi denunciado nas penas do inciso IV do par\u00e1grafo \u00fanico do art. 16 do Estatuto do Desarmamento.<\/p>\n<p>II. <strong>Exige-se concreta motiva\u00e7\u00e3o para a decreta\u00e7\u00e3o da pris\u00e3o preventiva, com base em fatos que efetivamente justifiquem a excepcionalidade da medida, atendendo-se aos termos do art. 312 do CPP e da jurisprud\u00eancia dominante.<\/strong><\/p>\n<p><strong>III. A possibilidade de abalo \u00e0 ordem p\u00fablica n\u00e3o pode ser sustentada por circunst\u00e2ncias que est\u00e3o subsumidas na gravidade do pr\u00f3prio tipo penal.<\/strong><br \/>IV. Condi\u00e7\u00f5es pessoais favor\u00e1veis, mesmo n\u00e3o sendo garantidoras de eventual direito \u00e0 liberdade provis\u00f3ria, devem ser devidamente valoradas, quando n\u00e3o demonstrada a presen\u00e7a de requisitos que justifiquem a medida constritiva excepcional.<\/p>\n<p>V. Recurso desprovido&quot; (5\u00aa. Turma do STJ, REsp 721416-SP, Rel. Min. Gilson Dipp, j. 18.08.2012, DJ 1000.0000.2012, p. 373) (destaques nossos).<\/p>\n<p>&quot;Ementa: CRIMINAL. HC. <strong>ESTATUTO DO DESARMAMENTO<\/strong>. ARTIGOS 17 E 21. <strong>VEDA\u00c7\u00c3O \u00c0 LIBERDADE PROVIS\u00d3RIA. AUS\u00caNCIA DE CONCRETA FUNDAMENTA\u00c7\u00c3O. NECESSIDADE DA CUST\u00d3DIA N\u00c3O DEMONSTRADA. ORDEM CONCEDIDA.<\/strong><\/p>\n<p><strong>I. Exige-se concreta motiva\u00e7\u00e3o para o indeferimento do benef\u00edcio da liberdade provis\u00f3ria, com base em fatos que efetivamente justifiquem a excepcionalidade da medida, atendendo-se aos termos do art. 312 do CPP e da jurisprud\u00eancia dominante.<\/strong><\/p>\n<p><strong>II. A exemplo do posicionamento aplicado por este Superior Tribunal de Justi\u00e7a aos crimes hediondos, o simples fato de se tratar da suposta pr\u00e1tica do crime previsto no art. 17 da Lei 10.826\/2003 n\u00e3o basta, por si s\u00f3, para impedir a liberdade provis\u00f3ria do r\u00e9u.<\/strong><\/p>\n<p>III. Ainda que as condi\u00e7\u00f5es pessoais favor\u00e1veis n\u00e3o sejam garantidoras de eventual direito \u00e0 liberdade provis\u00f3ria, <strong>estas devem ser devidamente valoradas quando n\u00e3o demonstrada a presen\u00e7a de requisitos que justifiquem a medida constritiva excepcional.<\/strong><\/p>\n<p>IV. Deve ser cassado o ac\u00f3rd\u00e3o do Tribunal de Justi\u00e7a do Estado do Rio Grande do Norte para <strong>restabelecer a decis\u00e3o monocr\u00e1tica concessiva da liberdade provis\u00f3ria ao paciente, sem preju\u00edzo de que venha a ser decretada novamente a cust\u00f3dia, com base em fundamenta\u00e7\u00e3o concreta<\/strong>.<br \/>V. Ordem concedida, nos termos do voto do Relator&quot; (5\u00aa. Turma do STJ, HC 43735-RN, Rel. Min. Gilson Dipp, j. 04.08.2012, DJ 2000.08.2012, p. 30000) (destaques nossos).<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Posto isto, o Minist\u00e9rio P\u00fablico opina no sentido de que seja <em>deferido<\/em> o pedido e, por conseq\u00fc\u00eancia, <em>concedida a liberdade provis\u00f3ria<\/em> ao custodiado (XXX), sem preju\u00edzo de que venha a ser posteriormente decretada medida cautelar, se evidenciados estiverem os motivos da pris\u00e3o processual, por entender ser de inteira Justi\u00e7a!<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00c9 o parecer.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Natal, 1000.01.2006.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong>PAULO GOMES PIMENTEL J\u00daNIOR<\/strong><\/p>\n<p><strong>68\u00b0. Promotor de Justi\u00e7a em Substitui\u00e7\u00e3o Legal<\/strong><\/p><\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[809],"class_list":["post-3054806","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo--liberdade-provisoria"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/3054806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=3054806"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=3054806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}