{"id":3026897,"date":"2024-06-07T23:08:51","date_gmt":"2024-06-07T23:08:51","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2024-06-07T23:08:51","modified_gmt":"2024-06-07T23:08:51","slug":"procuracao-judicial-e-extrajudicial-poderes-especiais","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/procuracao-judicial-e-extrajudicial-poderes-especiais\/","title":{"rendered":"[MODELO] Procura\u00e7\u00e3o Judicial e Extrajudicial  &#8211;  Poderes Especiais"},"content":{"rendered":"<p>PROCURA\u00c7\u00c3O AD JUDICIA ET EXTRA <\/p>\n<p><strong>OUTORGANTE:<\/strong> (Nome do Outorgante), (Nacionalidade), (Estado Civil), (Profiss\u00e3o), Carteira de Identidade n\u00ba (xxx), C.P.F. n\u00ba (xxx), residente e domiciliado na Rua (xxx), n\u00ba (xxx), bairro (xxx), Cep (xxx), Cidade (xxx), no Estado (xxx).<\/p>\n<p><strong>OUTORGADO:<\/strong> (Nome do Outorgado), (Nacionalidade), (Estado Civil), advogado, Carteira de Identidade n\u00ba (xxx), C.P.F. n\u00ba (xxx), inscrito na Ordem dos Advogados do Brasil sob o n\u00ba (xxx), Se\u00e7\u00e3o do Estado (xxx), Subse\u00e7\u00e3o (xxx), com escrit\u00f3rio profissional situado na Rua (xxx), n\u00ba (xxx), bairro (xxx), Cep (xxx), Cidade (xxx), no Estado.<\/p>\n<p>Atrav\u00e9s do presente instrumento particular de mandato, o <strong>OUTORGANTE<\/strong> nomeia e constitui como seu procurador o <strong>OUTORGADO<\/strong>, concedendo-lhe amplos poderes, inerentes ao bom e fiel cumprimento deste mandato, bem como para o foro em geral, conforme estabelecido no artigo 38 do C\u00f3digo de Processo Civil, e os especiais para transigir, fazer acordo, firmar compromisso, substabelecer, renunciar, desistir, reconhecer a proced\u00eancia do pedido, receber intima\u00e7\u00f5es, receber e dar quita\u00e7\u00e3o, praticar todos atos perante reparti\u00e7\u00f5es p\u00fablicas Federais, Estaduais e Municipais, e \u00f3rg\u00e3os da administra\u00e7\u00e3o p\u00fablica direta e indireta, praticar quaisquer atos perante particulares ou empresas privadas, recorrer a quaisquer inst\u00e2ncias e tribunais, podendo atuar em conjunto ou separadamente, dando tudo por bom e valioso, com fim espec\u00edfico para (descrever finalidade, tais como propor A\u00e7\u00e3o de (xxx) em face de (xxx)).<\/p>\n<p>(Local, Data e ano)<\/p>\n<p>(Nome e assinatura do Outorgante)<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[483],"class_list":["post-3026897","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-contratos"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/3026897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=3026897"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=3026897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}