{"id":3017952,"date":"2024-06-07T21:01:50","date_gmt":"2024-06-07T21:01:50","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2024-06-07T21:01:50","modified_gmt":"2024-06-07T21:01:50","slug":"liberacao-fgts-mandado-de-seguranca-contra-cef","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/liberacao-fgts-mandado-de-seguranca-contra-cef\/","title":{"rendered":"[MODELO] &#8220;Libera\u00e7\u00e3o FGTS: Mandado de seguran\u00e7a contra CEF&#8221;"},"content":{"rendered":"<p><strong>TRIBUNAL REGIONAL FEDERAL DA 2\u00aa REGI\u00c3O \u2013 1\u00aa TURMA<\/strong><\/p>\n<h1>REMESSA EX OFFICIO n\u00ba <\/h1>\n<p>PARTE A:\t<strong>e outros<\/strong><\/p>\n<p>PARTE R:\t<strong>CAIXA ECON\u00d4MICA FEDERAL- CEF<\/strong><\/p>\n<p>RELATOR:\t<strong>DES FEDERAL CARREIRA ALVIM<\/strong><\/p>\n<p><strong>Egr\u00e9gia Turma<\/strong><\/p>\n<p>\t\t\tTrata-se de mandado de seguran\u00e7a impetrado contra ato do SUPERINTENDENTE REGIONAL DA CAIXA ECON\u00d4MICA FEDERAL, objetivando a libera\u00e7\u00e3o dos saldos das contas vinculadas ao FUNDO DE GARANTIA POR TEMPO DE SERVI\u00c7O, tendo em vista a transforma\u00e7\u00e3o do regime jur\u00eddico dos p\u00fablicos civis, de celetista para estatut\u00e1rio.<\/p>\n<p>\t\t\tA senten\u00e7a julgou procedente o pedido.<\/p>\n<p>\t\t\tIrresignada, a CEF interp\u00f4s o recurso de apela\u00e7\u00e3o, tido por deserto pela decis\u00e3o de fls. 189.<\/p>\n<p>\t\t\t\u00c9 o relat\u00f3rio.<\/p>\n<p>\t\t\tAinda que controversa a aplicabilidade do verbete n\u00ba 178 da S\u00famula do extinto Tribunal Federal de Recursos<sup><a href=\"#footnote-2\" id=\"footnote-ref-2\">[1]<\/a><\/sup>, pac\u00edfico o entendimento segundo o qual, decorridos tr\u00eas anos desde a data da convers\u00e3o do regime jur\u00eddico celetista em estatut\u00e1rio, fazem os autores jus \u00e0 libera\u00e7\u00e3o de suas contas do FGTS:<\/p>\n<p>AGRAVO DE INSTRUMENTO &#8211; LIBERA\u00c7\u00c3O DO FGTS.<\/p>\n<p>I &#8211; Os servidores p\u00fablicos regidos pela CLT que, em virtude da edi\u00e7\u00e3o da Lei 8.112\/90, tiveram o seu regime de trabalho alterado, passando ao estatut\u00e1rio, faziam jus \u00e0 movimenta\u00e7\u00e3o de suas contas vinculadas de FGTS, a teor da S\u00famula 178 do extinto Tribunal Federal de Recursos.<\/p>\n<p>II &#8211; N\u00e3o pode a norma posterior, Lei 8.162\/91, retroagir para alcan\u00e7ar o direito adquirido dos servidores p\u00fablicos, intelig\u00eancia do art.5\u00ba, XXXVI da Constitui\u00e7\u00e3o Federal.<\/p>\n<p>III &#8211; Agravo de Instrumento improvido.<\/p>\n<p>(TRF \u2013 2\u00aa Regi\u00e3o \u2013 3\u00aa Turma \u2013 AG 27811 \u2013 Processo: 98.02.11608-1 RJ \u2013 Data da Decis\u00e3o: 08\/02\/2000 \u2013 Relator XXXXXXXXXXXXA TANIA HEINE)<\/p>\n<p>PROCESSUAL CIVIL &#8211; CAUTELAR &#8211; SAQUE DO FGTS &#8211; CONVERS\u00c3O DO REGIME JUR\u00cdDICO DE CELETISTA PARA ESTATUT\u00c1RIO &#8211; DECURSO DE PRAZO SUPERIOR A TR\u00caS ANOS &#8211; LIBERA\u00c7\u00c3O &#8211; SINDICATO &#8211; LEGITIMIDADE ATIVA &quot;AD CAUSAM&quot; &#8211; SUBSTITUI\u00c7\u00c3O PROCESSUAL &#8211; ART. 5\u00ba, XXI, DA CF\/88.<\/p>\n<p>I) EST\u00c1 O SINDICATO LEGITIMADO A DEFENDER DIREITOS INDIVIDUAIS DOS ASSOCIADOS, EXISTENTES EM RAZ\u00c3O DAS ATIVIDADES POR ELES EXERCIDAS, DESDE QUE EXPRESSAMENTE AUTORIZADO, NOS TERMOS DO ART. 5\u00ba, XXI, DA CF\/88.<\/p>\n<p>II) <strong>LEGITIMIDADE PASSIVA &quot;AD CAUSAM&quot; EXCLUSIVA DA CEF PARA RESPONDER DEMANDAS ACERCA DO FGTS.<\/strong> PRECEDENTES DO E. SUPERIOR TRIBUNAL DE JUSTI\u00c7A. <strong>EXCLUS\u00c3O DA UNI\u00c3O FEDERAL E DO BANCO DO BRASIL<\/strong> DO P\u00d3LO PASSIVO DA LIDE.<\/p>\n<p>III) DECORRIDO PRAZO SUPERIOR A TR\u00caS ANOS DESDE A CONVERS\u00c3O DO REGIME CELETISTA DOS SUBSTITU\u00cdDOS, FAZEM ESTES JUS \u00c0 LIBERA\u00c7\u00c3O DE SEU FGTS, N\u00c3O HAVENDO MAIS QUALQUER CONTROV\u00c9RSIA A SER OBJETO DE RECURSO, ESTANDO PREJUDICADO O SEU CONHECIMENTO.<\/p>\n<p>IV) RECURSO DA CEF E DA UNI\u00c3O FEDERAL N\u00c3O CONHECIDOS. REMESSA &quot;EX OFFICIO&quot; PROVIDA PARA EXCLUIR A UNI\u00c3O FEDERAL DO FEITO.<\/p>\n<p>(TRF \u2013 2\u00aa Regi\u00e3o \u2013 8\u00aa Turma \u2013 AC Processo: 99.02.00882-3 RJ \u2013Data da Decis\u00e3o: 21\/06\/2012 \u2013 Relator XXXXXXXXXXXX ROGERIO CARVALHO)<\/p>\n<p>\t\t\tDo exposto, o parecer \u00e9 no sentido da confirma\u00e7\u00e3o da senten\u00e7a.<\/p>\n<p>\t\t\tRio de Janeiro, <\/p>\n<ol>\n<li id=\"footnote-2\">\n<p> \u201cResolvido o contrato de trabalho com a transfer\u00eancia do servidor do regime da CLT para o estatut\u00e1rio, em decorr\u00eancia da lei, assiste-lhe o direito de movimentar a conta vinculada do FGTS\u201d. <a href=\"#footnote-ref-2\">\u2191<\/a><\/p>\n<\/li>\n<\/ol>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[154],"class_list":["post-3017952","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-previdenciario"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/3017952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=3017952"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=3017952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}