{"id":29631,"date":"2023-07-29T00:18:00","date_gmt":"2023-07-29T00:18:00","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-29T00:18:00","modified_gmt":"2023-07-29T00:18:00","slug":"pedido-de-reconsideracao-do-despacho-e-concessao-de-tutela-antecipada-para-re-ligacao-da-linha-telefonica-com-multa-cominatoria","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/pedido-de-reconsideracao-do-despacho-e-concessao-de-tutela-antecipada-para-re-ligacao-da-linha-telefonica-com-multa-cominatoria\/","title":{"rendered":"[MODELO] Pedido de reconsidera\u00e7\u00e3o do despacho e concess\u00e3o de tutela antecipada para re &#8211; liga\u00e7\u00e3o da linha telef\u00f4nica com multa cominat\u00f3ria"},"content":{"rendered":"<p>EXMO. SR. DR. JUIZ DE DIREITO DO I JUIZADO ESPECIAL C\u00cdVEL DA COMARCA DA CAPITAL.<\/p>\n<h1>Processo n\u00ba <\/h1>\n<p><strong>\t\t<\/strong>, nos autos do processo que move em face \u00e0 TELEMAR S.A, por seu advogado infra-assinado, vem, respeitosamente, \u00e0 presen\u00e7a de V.Exa., solicitar a <strong>RECONSIDERA\u00c7\u00c3O DO DESPACHO<\/strong> \u00e0s fls. 41, pelos fatos a seguir expostos:<\/p>\n<ol>\n<li>\u00c9 o \u00fanico telefone da casa e tem al\u00e9m do uso familiar, a utiliza\u00e7\u00e3o para contatos de trabalho, visto o autor ser aut\u00f4nomo, e ter no telefone sua ferramenta principal de trabalho.<\/li>\n<li>A audi\u00eancia de concilia\u00e7\u00e3o ser\u00e1 no dia 13 de janeiro, e caso n\u00e3o tenha sucesso no seu pedido de tutela, passar\u00e1 Natal e Ano Novo impossibilitado de se comunicar e ser contactado pelo telefone.<\/li>\n<\/ol>\n<p>Dessa forma, requer a reconsidera\u00e7\u00e3o do referido despacho, concedendo a tutela antecipada, intimando da r\u00e9 para, no prazo de 24 horas, providenciar a re-liga\u00e7\u00e3o da linha telef\u00f4nica, de n\u00famero 2424-8546 sob pena de multa cominat\u00f3ria, para que seja feita a JUSTI\u00c7A. <\/p>\n<p>\t\tNestes termos,<\/p>\n<p>\t\tP. deferimento.<\/p>\n<p>\t\tRio de Janeiro, <\/p><\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[142],"class_list":["post-29631","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-civel"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/29631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=29631"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=29631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}