{"id":29536,"date":"2023-07-29T00:16:20","date_gmt":"2023-07-29T00:16:20","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-29T00:16:20","modified_gmt":"2023-07-29T00:16:20","slug":"alegacoes-finais-fato-cometido-sob-coacao-irresistivel-ou-obediencia-a-ordem-hierarquica","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/alegacoes-finais-fato-cometido-sob-coacao-irresistivel-ou-obediencia-a-ordem-hierarquica\/","title":{"rendered":"[MODELO] Alega\u00e7\u00f5es Finais  &#8211;  Fato Cometido Sob Coa\u00e7\u00e3o Irresist\u00edvel ou Obedi\u00eancia a Ordem Hier\u00e1rquica"},"content":{"rendered":"<p><strong>ALEGA\u00c7\u00d5ES FINAIS<\/strong> &#8211; fato cometido sob <strong>coa\u00e7\u00e3o irresist\u00edvel<\/strong> ou em estrita obedi\u00eancia de ordem, n\u00e3o manifestamente ilegal, de <strong>superior hier\u00e1rquico<\/strong>, s\u00f3 \u00e9 pun\u00edvel o autor da coa\u00e7\u00e3o ou da ordem.\u201d<\/p>\n<p><strong>EXMO.  SR.  DR.  JUIZ  DE  DIREITO DA &#8230; VARA CRIMINAL DA COMARCA  DE &#8230;&#8230;  ESTADO  DE  &#8230;<\/strong><\/p>\n<p>Processo n.\u00ba&#8230;.<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;, qualificado nos autos do processo em ep\u00edgrafe, por seu procurador que esta subscreve, vem, com o mais fidald\u00edgno respeito \u00e0 presen\u00e7a de V. Exa., com suped\u00e2neo no art. 500, do CPP, apresentar suas<\/p>\n<p> <strong>ALEGA\u00c7\u00d5ES FINAIS<\/strong>, ante os motivos f\u00e1ticos e jur\u00eddicos, quer sejam objetivos ou subjetivos que abaixo ser\u00e3o relatados:<\/p>\n<p>Antes de mais nada, h\u00e1 que salientarmos que o Magistrado deve manter o seu esp\u00edrito sereno, absolutamente livre de sugest\u00e3o de qualquer natureza, para que aprecie e conseq\u00fcentemente julgue o processo na competente Justi\u00e7a dos Homens; mas com o discernimento e ilumina\u00e7\u00e3o da Justi\u00e7a Divina.<\/p>\n<p>Que o r\u00e9u&#8230;&#8230;&#8230;&#8230; juntamente com o co-r\u00e9u &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; fora Denunciado pelo Minist\u00e9rio P\u00fablico (fls. .. do Processo), sendo aludida Den\u00fancia recebida por V. Exa., \u00e0s  fls. &#8230;<\/p>\n<p>Os r\u00e9us foram reconhecidos pela v\u00edtima o Sr. &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. e a testemunha de acusa\u00e7\u00e3o o Sr&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;., tanto na fase inquisitiva (fls&#8230;&#8230;.), como na judicial (fls. &#8230;..).<\/p>\n<p>Por\u00e9m, MM., em momento algum o Defendente fora encontrado em posse quer seja direta ou indireta da  \u201cres furtiva\u201d, ou da arma de fogo que supostamente fora utilizada na realiza\u00e7\u00e3o do crime, conforme pode-se notar no depoimento prestado pelos policiais que autuaram os r\u00e9us em Flagrante de Delito (fls. &#8230;&#8230;).<\/p>\n<p>Fora pleiteado pelo defensor do r\u00e9u, ora Defendente, a reinquiri\u00e7\u00e3o da v\u00edtima e da testemunha mencionada no item 03 (tr\u00eas) retro, sendo que referido pedido fora negado por V. Exa., por\u00e9m, pertinente salientarmos que, se a v\u00edtima e referida testemunha puderem ser novamente ouvidas, esclarecer-se-\u00e3o fatos que, sem d\u00favida nenhuma poder\u00e3o absolver o Defendente, ou na pior das hip\u00f3teses poder\u00e1 atenuar a pena que o mesmo vir\u00e1 a sofrer se for condenado.<\/p>\n<p>Mencionou a v\u00edtima, em conversa informal com os pais do Defendente, o seguinte:<\/p>\n<p>\u201cQue o  \u201cmoreninho\u201d praticamente n\u00e3o participou do assalto, pois ficou o tempo todo agachado \u00e0 beira da sarjeta, dizendo ao \u201cAlem\u00e3o\u201d: \u201cVamos embora cara\u201d, \u201cdeixa disso\u201d, e que mesmo assim nada adiantou, pois o \u201calem\u00e3o\u201d insistiu no assalto.\u201d<\/p>\n<p>Ante a declara\u00e7\u00e3o informal retro mencionada, podemos com a mais absoluta clareza concluirmos que o Defendente fora coagido a participar do delito, objeto da acusa\u00e7\u00e3o. Diante dessa coa\u00e7\u00e3o, o C\u00f3digo Penal em seu art. 22, disp\u00f5e o seguinte:<\/p>\n<p>\u201cSe o fato \u00e9 cometido sob coa\u00e7\u00e3o irresist\u00edvel ou em estrita obedi\u00eancia de ordem, n\u00e3o manifestamente ilegal, de superior hier\u00e1rquico, s\u00f3 \u00e9 pun\u00edvel o autor da coa\u00e7\u00e3o ou da ordem.\u201d<\/p>\n<p>A interpreta\u00e7\u00e3o jurisprudencial desse art., encontra-se na obra de Alberto Silva Franco, na qual relata o seguinte:\t\t\t<\/p>\n<p>\u201cA coa\u00e7\u00e3o moral irresist\u00edvel \u00e9 uma das hip\u00f3teses  da exclus\u00e3o da culpabilidade, na qual o coacto, em raz\u00e3o de constrangimento moral que sobre ele \u00e9 exercido, atua em condi\u00e7\u00f5es anormais, de forma que n\u00e3o se lhe pode exigir um comportamento, de acordo com a ordem jur\u00eddica. O constrangimento moral deve ser irresist\u00edvel e por irresist\u00edvel, segundo o Des. Cunha Camargo (JUTACRIM 44\/412), se entende o constrangimento \u201cinevit\u00e1vel, insuper\u00e1vel ou inelut\u00e1vel\u201d, \u201cuma for\u00e7a de que o coacto n\u00e3o se pode subtrair, tudo sugerindo situa\u00e7\u00e3o \u00e0 qual ele n\u00e3o pode se opor, recusar-se ou fazer face, mas t\u00e3o somente sucumbir, ante o decreto do inexor\u00e1vel\u201d. Se a coa\u00e7\u00e3o moral for, no entanto, resist\u00edvel, limitar\u00e1 em favor do agente uma atenuante (art. 65, III, \u201cc\u201d, do C\u00f3d.  Penal.\u201d<\/p>\n<p>\u201cA coa\u00e7\u00e3o moral irresist\u00edvel de que cuida a Lei Penal, consiste no emprego de grave amea\u00e7a contra algu\u00e9m, no sentido de que realize um ato ou n\u00e3o (Dam\u00e1sio, Direito Penal, 1\u00ba\/444).\u201d<\/p>\n<p>\u201cO temor de um dano injusto e grave \u00e0 sua pessoa ou a aqueles que lhes s\u00e3o caros \u00e9 que compele ao coagido a praticar o delito\u201d (An\u00edbal Bruno, Direito Penal, 2\u00ba\/271). (TJSP &#8211; Ver. &#8211; Rel. Weiss de Andrade &#8211; RJTJSP 76\/349 e RT 557\/303).<\/p>\n<p>\u201cA inexistibilidade da coa\u00e7\u00e3o esta em que o coagido n\u00e3o pode venc\u00ea-la, por ter ocorrido a supress\u00e3o da liberdade de agir, em sentido oposto \u00e0 liberdade do coator\u201d(TJSP &#8211; EI &#8211; Rel. Onei Raphael &#8211; RT 410\/100).<\/p>\n<p>\u201c\u00c9 irresist\u00edvel a coa\u00e7\u00e3o quando n\u00e3o pode ser superada sen\u00e3o com uma energia extraordin\u00e1ria e, portanto, juridicamente inexig\u00edvel\u201d (TACRIM\/SP &#8211; AC. &#8211; Rel. Adalberto Spagnuollo &#8211; RT 501\/282).<\/p>\n<p>\u201cA excludente da coa\u00e7\u00e3o moral irresist\u00edvel n\u00e3o pode ser invocada sem a presen\u00e7a de tr\u00eas pessoas distintas e inconfund\u00edveis: do agente coacto, do coator e da v\u00edtima\u201d(TJMG &#8211; AC. &#8211; Rel. Sylvio Lemos &#8211; RT 507\/445).<\/p>\n<p>\u201cPara que se configure a coa\u00e7\u00e3o moral irresist\u00edvel, indispens\u00e1vel se torna a presen\u00e7a de tr\u00eas elementos: o coator, o coagido e a v\u00edtima\u201d(TJMT &#8211; AC. &#8211; Rel. Otair da Cruz Bandeira &#8211; RT 508\/399).<\/p>\n<p>Passamos a exibir o coment\u00e1rio doutrin\u00e1rio da obra Princ\u00edpios B\u00e1sicos do Direito Penal, de Francisco de Assis Toledo: <\/p>\n<p>\u201c&#8230;na coa\u00e7\u00e3o moral, o coagido tem suas possibilidades de op\u00e7\u00e3o bastante restringidas pelo temor de sofrer algum mal, n\u00e3o obstante age ou omite, impelido pelo medo, valendo-se de suas pr\u00f3prias for\u00e7as. Se essa forma de coa\u00e7\u00e3o, ou seja, a vis compulsiva, for igualmente irresist\u00edvel \u00e0 vis absoluta, exclui-se a culpabilidade do coagido, por n\u00e3o lhe ser exigida, nas circunst\u00e2ncias, conduta diversa que realizou.\u201d <\/p>\n<p>Para refor\u00e7armos, ainda, a tese de que o Defendente foi coagido a participar do referido roubo, faremos as seguintes indaga\u00e7\u00f5es: <\/p>\n<p>a) Como poderia ter o Defendente vontade em agir da forma que agiu se a todo momento dizia ao co-r\u00e9u \u201cdeixa pra l\u00e1\u201d; \u201cvamos embora\u201d ? <\/p>\n<p>b) Ainda, como poderia o Defendente ter participa\u00e7\u00e3o efetiva no mencionado crime, se em momento algum, proferiu qualquer amea\u00e7a \u00e0 v\u00edtima, permanecendo inerte, agachado \u00e0 beira da sarjeta, como se estivesse a meditar \u201cpor que eu estou aqui\u201d <\/p>\n<p>Pode, ainda, a Ilustre Representante do Minist\u00e9rio P\u00fablico, em seu papel de acusadora, indagar o seguinte:<\/p>\n<p>\u201cMas, se o r\u00e9u ora Defendente \u00e9 inocente, ou foi coagido, por que n\u00e3o mencionou aludida coa\u00e7\u00e3o nas fases anteriores do processo ?\u201d<\/p>\n<p>\u00c9 l\u00f3gico que o mesmo n\u00e3o tinha como provar tal alega\u00e7\u00e3o; at\u00e9 que seus pais, em conversa informal com a v\u00edtima, puderam perceber que tal prova se encontrava no pr\u00f3prio depoimento em que a v\u00edtima pudesse vir a dar para esclarecer o acima alegado. Sem contar, que quando uma pessoa est\u00e1 sendo de alguma forma amea\u00e7ada, n\u00e3o tem controle de suas atitudes e reflexos.<\/p>\n<p>Passamos a abordar o conhecimento cient\u00edfico, delineado na obra Psicoterapia, de Paul A. Dewald, Professor de Psicopatologia do Chicago Institute for Psychoanalysis e da St. Louis University School of Medicine, tradu\u00e7\u00e3o feita por Helena Mascarenhas de Souza, que abaixo ilustra essa pe\u00e7a:<\/p>\n<p>Estudo sobre o medo, fobia e p\u00e2nico &#8211;<\/p>\n<p>\u201cUm indiv\u00edduo quando se depara em uma situa\u00e7\u00e3o de medo\/fobia, ou uma situa\u00e7\u00e3o de ansiedade muito intensa, ocorre a perda de consci\u00eancia, onde deixa de agir com a raz\u00e3o, utilizando-se de outros recursos preexistentes, ou at\u00e9 mesmo algo que estava armazenado no inconsciente (Id.); fazendo com que o mesmo indiv\u00edduo cometa atos anti-sociais, ou at\u00e9 mesmo atos anti-jur\u00eddicos, isto \u00e9, criminosos.\u201d<\/p>\n<p>\u201cOs impulsos ocorrem, quando o ser humano, diante de um fato inesperado, ou que suas quest\u00f5es morais n\u00e3o permitem agir, fica perturbado, sem equil\u00edbrio, situa\u00e7\u00e3o em que o superego n\u00e3o funciona, para tomar as atitudes coerentes e condizentes com sua conduta em estado normal. Ficando em conflito diante do que \u00e9 moral ou imoral.\u201d<\/p>\n<p>\u201cUm indiv\u00edduo quando est\u00e1 em situa\u00e7\u00e3o de obrigatoriedade ou se sente coagido; se encontra imobilizado, sem alternativa, sendo levado a tomar atitudes que n\u00e3o faz parte de sua \u00edndole.\u201d<\/p>\n<p>Menciona, ainda, Charles Brenner, em sua obra Psicologia Psicanal\u00edtica, Cap\u00edtulo &#8211; No\u00e7\u00f5es B\u00e1sicas da Psican\u00e1lise, o seguinte:<\/p>\n<p>\u201cAng\u00fastia ante um perigo real \u00e9 o termo utilizado por Freud no quadro da sua segunda teoria da ang\u00fastia; perante um perigo exterior que constitui para o sujeito uma amea\u00e7a real.\u201d<\/p>\n<p>\u201cAng\u00fastia autom\u00e1tica \u00e9 a rea\u00e7\u00e3o do sujeito sempre que se encontra numa situa\u00e7\u00e3o traum\u00e1tica, isto \u00e9, submetido a um fluxo de excita\u00e7\u00f5es, de origem externa ou interna, que \u00e9 incapaz de dominar. A ang\u00fastia autom\u00e1tica op\u00f5e-se para Freud ao sinal de ang\u00fastia.\u201d<\/p>\n<p>MM., sem desmerecer o farto conhecimento e a ampla experi\u00eancia que tem V. Exa., data venia, se olhares de forma simples e objetiva para os fatos, fatalmente condenar\u00e1s o Defendente, mas, se olhares atento aos labirintos que a subjetividade em crimes como o que o Defendente est\u00e1 sendo imputado, o absolver\u00e1, sem sombra de d\u00favida.<\/p>\n<p>N\u00e3o podemos repudiar, \u00e0queles que foram criminalmente processados, e por serem inocentes, foram absolvidos. \u00c9 sabido tamb\u00e9m da primariedade do Defendente, independentemente do fato de ter sido processado anteriormente, pois o mesmo foi absolvido, por comprovada inoc\u00eancia.<\/p>\n<p>Diante dessa linha de racioc\u00ednio, se o Defendente fora coagido, n\u00e3o \u00e9 co-autor do crime, e sim mais uma v\u00edtima da viol\u00eancia que circunda nossa popula\u00e7\u00e3o. Portanto, n\u00e3o agiu com vontade pr\u00f3pria, assim, salutar a inexist\u00eancia da qualificadora delineada no inciso II, \u00a7 2.\u00ba, art. 157 do C\u00f3digo Penal; e, ainda, n\u00e3o usou de amea\u00e7a, ficando t\u00e3o e somente agachado \u00e0 beira da sarjeta, portanto, n\u00e3o existe a figura da qualificadora explicitada no inciso I da mesma norma legal. <\/p>\n<p>Conforme j\u00e1 o disse, na pior das hip\u00f3teses, se a coa\u00e7\u00e3o for considerada resist\u00edvel, e o Defendente for condenado, devemos ter como entendimento de que n\u00e3o existem os pressupostos que configurem a qualificadora, portanto, a pena dever\u00e1 ser aplicada em seu m\u00ednimo, com os devidos atenuantes delineados no art. 65, III, c, do C\u00f3digo Penal.<\/p>\n<p>Pertinente relatarmos, ainda, que a v\u00edtima recuperou em sua totalidade o patrim\u00f4nio que fora subtra\u00eddo na ocasi\u00e3o dos fatos, portanto, n\u00e3o h\u00e1 que falarmos em repara\u00e7\u00e3o material. <\/p>\n<p>Douto Juiz, o Defendente deve estar se sentindo realmente muito amea\u00e7ado, pois, em momento algum contou a este que esta subscreve, o que ocorreu, e o que o levou a supostamente praticar tal delito.<\/p>\n<p>Diante de todo o exposto, quer seja Legisla\u00e7\u00e3o, Doutrina, Jurisprud\u00eancia, Conhecimentos Espec\u00edficos, e da clareza dos fatos que demonstram ato coercitivo que envolveu o Defendente, vem com a mais enaltecida rever\u00eancia, pedir \u00e0 V. Exa. a absolvi\u00e7\u00e3o do r\u00e9u &#8230;&#8230;., e se o MM. Juiz, n\u00e3o entender que o mesmo n\u00e3o seja merecedor da Absolvi\u00e7\u00e3o, julgue-o de forma que tenha sua pena atenuada, para que se cumpra o verdadeiro papel do Poder Judici\u00e1rio, ou seja, que se fa\u00e7a <\/p>\n<p>J   U   S   T   I   \u00c7   A <\/p>\n<p>Advogado OAB\/&#8230;..<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[142],"class_list":["post-29536","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-civel"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/29536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=29536"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=29536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}