{"id":28425,"date":"2023-07-28T23:49:13","date_gmt":"2023-07-28T23:49:13","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-28T23:49:13","modified_gmt":"2023-07-28T23:49:13","slug":"acao-revisional-de-alimentos-alteracao-do-valor-de-pensao","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/acao-revisional-de-alimentos-alteracao-do-valor-de-pensao\/","title":{"rendered":"[MODELO] A\u00e7\u00e3o Revisional de Alimentos  &#8211;  Altera\u00e7\u00e3o do Valor de Pens\u00e3o"},"content":{"rendered":"<h1><strong>EXCELENT\u00cdSSIMO Senhor DOUTOR JUIZ DE DIREITO DA &#8230;.. a VARA &#8230;&#8230;&#8230;&#8230;&#8230; DO FORO &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. <\/strong><\/h1>\n<p><strong> <\/strong><\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.\u2026\u2026\u2026\u2026.. (nome completo), \u2026&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. (nacionalidade), &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. (estado civil), &#8230;&#8230;&#8230;&#8230;&#8230;.. (profiss\u00e3o), portador da c\u00e9dula de identidade RG no &#8230;&#8230;&#8230;&#8230;&#8230;.., inscrito no CPF sob no &#8230;&#8230;&#8230;&#8230;.., residente e domiciliado na cidade de &#8230;&#8230;&#8230;&#8230;&#8230;. (munic\u00edpio e UF), \u00e0 &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; (endere\u00e7o completo: rua [av.], no, complemento, bairro, CEP, UF), , por seu Advogado que esta subscreve, constitu\u00eddo na forma do incluso instrumento de mandato (doc. &#8230;&#8230;..), com endere\u00e7o profissional \u00e0 &#8230;&#8230;&#8230;\u2026\u2026\u2026&#8230;&#8230;. (endere\u00e7o completo: rua [av.], no, complemento, bairro, cidade, CEP, UF),  onde receber\u00e1 as intima\u00e7\u00f5es para os atos judiciais, vem, respeitosamente, \u00e0 honrosa presen\u00e7a de Vossa Excel\u00eancia propor a presente <\/p>\n<\/p>\n<h2><strong>A\u00c7\u00c3O REVISIONAL DE ALIMENTOS <\/strong><\/h2>\n<\/p>\n<p>em face de ..\u2026\u2026&#8230;&#8230;. (nome completo), &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. (nacionalidade), &#8230;&#8230;&#8230;&#8230;&#8230;.. (estado civil), &#8230;&#8230;&#8230;&#8230;&#8230;. (profiss\u00e3o), residente e domiciliada na cidade de &#8230;&#8230;&#8230;&#8230;&#8230;.. (munic\u00edpio e UF), \u00e0 &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; (endere\u00e7o completo: rua [av.], no, complemento, bairro, CEP, UF), , neste ato representando legalmente o filho menor (im)p\u00fabere do casal, pelos motivos de fatos e de direito a seguir aduzidos: <\/p>\n<\/p>\n<p>1 \u2013 O Requerente e a Requerida encontram-se divorciados desde &#8230;&#8230;&#8230;&#8230;&#8230; (dia, m\u00eas e ano), conforme certid\u00e3o de casamento em que est\u00e1 devidamente averbado o div\u00f3rcio, em anexo (doc. &#8230;&#8230;). <\/p>\n<\/p>\n<p>2 \u2013 Na referida a\u00e7\u00e3o de div\u00f3rcio foi homologado acordo de alimentos em que o Requerente comprometeu-se a pagar &#8230;.% (&#8230;. por cento) de seus rendimentos l\u00edquidos, a t\u00edtulo de alimentos, para seu filho. <\/p>\n<\/p>\n<p>3 \u2013 Posteriormente, o Requerente reconstruiu sua vida afetiva, casou-se novamente e tem mais &#8230;&#8230;&#8230; (por extenso) filhos, conforme certid\u00f5es de casamento e nascimento em anexo (docs. &#8230;&#8230;.). <\/p>\n<\/p>\n<p>4 \u2013 Quando do acordo de alimentos, a ex-esposa do requerente n\u00e3o exercia nenhuma atividade remunerada. Hoje est\u00e1 formada em &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;, e trabalha como &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.., auferindo uma renda mensal de R$ &#8230;&#8230;&#8230;&#8230;&#8230;.. (valor por extenso), conforme demonstrativo de pagamento em anexo (doc. &#8230;.). <\/p>\n<\/p>\n<p>5 \u2013 Diante do aumento do compromisso com a nova fam\u00edlia, o Requerente vem passando por s\u00e9rias dificuldades financeiras, o que torna praticamente imposs\u00edvel honrar o acordo de alimentos firmado anteriormente. <\/p>\n<\/p>\n<p>6 \u2013 Conforme disp\u00f5e o art. 1.699 do C\u00f3digo Civil: <\/p>\n<p><em> <\/em><\/p>\n<p><em>\u201cSe, fixados os alimentos, sobrevier mudan\u00e7a na situa\u00e7\u00e3o financeira de quem os supre, ou na de quem os recebe, poder\u00e1 o interessado reclamar ao juiz, conforme as circunst\u00e2ncias, exonera\u00e7\u00e3o, redu\u00e7\u00e3o ou majora\u00e7\u00e3o do encargo.\u201d <\/em><\/p>\n<p>Pelo o exposto, REQUER: <\/p>\n<\/p>\n<ol>\n<li><strong>a) <\/strong> A cita\u00e7\u00e3o do Alimentado no endere\u00e7o declinado no pre\u00e2mbulo desta inicial, para que compare\u00e7a \u00e0 audi\u00eancia de concilia\u00e7\u00e3o a ser designada, decorrendo da\u00ed o prazo para contestar, se quiser, sob pena de confiss\u00e3o e efeitos da revelia; <\/li>\n<\/ol>\n<p><strong>b) <\/strong> A intima\u00e7\u00e3o do ilustre representante do Minist\u00e9rio P\u00fablico para atuar no feito; <\/p>\n<\/p>\n<p><strong>c) <\/strong>A redu\u00e7\u00e3o dos alimentos prestados para o percentual de &#8230;..% (&#8230; por cento) de sua remunera\u00e7\u00e3o l\u00edquida; <\/p>\n<\/p>\n<p><strong>d)<\/strong> A produ\u00e7\u00e3o de todos os meios de prova em direito admitidos, inclusive depoimento pessoal da Requerida, juntada de documentos, oitiva de testemunhas, per\u00edcias, expedi\u00e7\u00e3o de of\u00edcios e precat\u00f3rias e demais provas que se fizerem necess\u00e1rias; <\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>e)<\/strong> A condena\u00e7\u00e3o da Requerida nas custas processuais e honor\u00e1rios advocat\u00edcios. <\/p>\n<\/p>\n<p>Autor\/requerente aberto \u00e0 concilia\u00e7\u00e3o\/media\u00e7\u00e3o, conforme a nova sistem\u00e1tica da Lei 13.105 de 2015.<\/p>\n<p>D\u00e1 \u00e0 causa o valor de R$ &#8230;&#8230;&#8230;&#8230;&#8230; (valor por extenso, sendo correspondente a uma anuidade sobre a redu\u00e7\u00e3o pleiteada). <\/p>\n<\/p>\n<p>Nestes Termos, <\/p>\n<h3>Pede deferimento. <\/h3>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;., &#8230;.. de &#8230;&#8230;&#8230;&#8230;&#8230;&#8230; de &#8230;&#8230;&#8230;&#8230;..  <\/p>\n<p>(local e Data) <\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; <\/p>\n<p>Advogado (nome) <\/p>\n<p>                              OAB\/ &#8230;.. no &#8230;&#8230;.. <\/p><\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[142],"class_list":["post-28425","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-civel"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/28425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=28425"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=28425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}