{"id":21817,"date":"2023-07-14T19:31:39","date_gmt":"2023-07-14T19:31:39","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-14T19:31:39","modified_gmt":"2023-07-14T19:31:39","slug":"acao-de-revisao-de-aluguel-de-locacao-residencial-sumario","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/acao-de-revisao-de-aluguel-de-locacao-residencial-sumario\/","title":{"rendered":"[MODELO] A\u00c7\u00c3O DE REVIS\u00c3O DE ALUGUEL DE LOCA\u00c7\u00c3O RESIDENCIAL (SUM\u00c1RIO)"},"content":{"rendered":"<p><strong>A\u00c7\u00c3O DE REVIS\u00c3O PARA ATUALIZA\u00c7\u00c3O DE ALUGUEL DE LOCA\u00c7\u00c3O RESIDENCIAL ( PROCEDIMENTO SUM\u00c1RIO )<\/strong><\/p>\n<p>EXCELENT\u00cdSSIMO SENHOR DOUTOR JUIZ DE DIREITO DA VARA C\u00cdVEL DA COMARCA _______<\/p>\n<p>(m\u00ednimo 12 espa\u00e7os)<\/p>\n<p>                 ____________, brasileiro, casado, motorista, residente e domiciliado nesta cidade, na rua ______________________, n.\u00ba ______, por seu procurador (Doc. 1), infra-escrito, vem perante Vossa Excel\u00eancia para propor, contra __________________________________, brasileiro, casado, banc\u00e1rio, residente e domiciliado nesta cidade, na rua _______________________________________, n.\u00ba _________, A\u00c7\u00c3O DE REVIS\u00c3O PARA ATUALIZA\u00c7\u00c3O DE ALUGUEL DE LOCA\u00c7\u00c3O RESIDENCIAL, pelo rito sum\u00e1rio, em raz\u00e3o dos  seguintes fatos e fundamentos: <\/p>\n<p>1. O Requerente \u00e9 propriet\u00e1rio e locador do im\u00f3vel sito nesta cidade, na rua _________________________, n.\u00ba _______, que se encontra locado ao requerido, por prazo indeterminado, com aluguel mensal no valor de         $ _______________________________ (_______________________________), com reajuste anual (Doc. 2 e 3); <\/p>\n<p>2. A presente loca\u00e7\u00e3o, para fins residenciais, data de ______________________________, portanto, h\u00e1 mais de 3 (tr\u00eas) anos de vig\u00eancia; 3. N\u00e3o tendo chegado a um entendimento com o Requerido para o fim de atualizar o valor locat\u00edcio do referido im\u00f3vel, ao valor de mercado, pretende, o Requerente, a corre\u00e7\u00e3o do aluguel mediante arbitramento judicial com fundamento nos arts. 19 e 68 da Lei n.\u00ba 8.245\/91.<\/p>\n<p>Ante o exposto requer: <\/p>\n<p>a) a cita\u00e7\u00e3o do requerido para, no prazo legal, contestar a presente a\u00e7\u00e3o sob pena de revelia e confiss\u00e3o; <\/p>\n<p>b) a proced\u00eancia da a\u00e7\u00e3o, com a atualiza\u00e7\u00e3o do valor mensal do aluguel para        $ ________________ (___________________________), ou o valor apurado em per\u00edcia, se superior ao pretendido, a ser pago a partir da cita\u00e7\u00e3o do Requerido, acrescido de corre\u00e7\u00e3o monet\u00e1ria, custas, honor\u00e1rios advocat\u00edcios e demais comina\u00e7\u00f5es legais.<\/p>\n<p>c) a fixa\u00e7\u00e3o de aluguel provis\u00f3rio, no valor de 80% do valor total solicitado, a partir da cita\u00e7\u00e3o do Requerido.<\/p>\n<p>Protesta pela produ\u00e7\u00e3o de provas judiciais, depoimento pessoal do Requerido, ouvida de testemunhas, documentos e per\u00edcias em geral.<\/p>\n<p>Valor da causa: R$ _________ (________________).<\/p>\n<p>N. termos E. Deferimento <\/p>\n<p>____________ de ____________ de 20____.<\/p>\n<p>Assinatura com n.\u00ba na OAB.<\/p>\n<p>_______________________________ <\/p>\n<p>OBSERVA\u00c7\u00d5ES: <\/p>\n<p>a) Esta a\u00e7\u00e3o cabe somente ap\u00f3s 3 anos de loca\u00e7\u00e3o.<\/p>\n<p>b) A vig\u00eancia do novo pre\u00e7o do aluguel, arbitrado pelo juiz, se d\u00e1 a partir da cita\u00e7\u00e3o.<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[935],"class_list":["post-21817","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-acoes"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/21817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=21817"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=21817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}