{"id":19659,"date":"2023-07-14T19:03:33","date_gmt":"2023-07-14T19:03:33","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-14T19:03:33","modified_gmt":"2023-07-14T19:03:33","slug":"prazo-para-a-parte-sanar-irregularidade-esfera-processual-civil","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/prazo-para-a-parte-sanar-irregularidade-esfera-processual-civil\/","title":{"rendered":"[MODELO] Prazo para a parte sanar irregularidade  &#8211;  Esfera Processual Civil"},"content":{"rendered":"<p>Esfera Processual Civil<\/p>\n<p>Prazo para a parte sanar irregularidade<\/p>\n<p>Excelent\u00edssimo Senhor Doutor XXXXXXXXXXXX de Direito da Comarca de &#8230;&#8230;.<\/p>\n<p>Diz Fulano de Tal, j\u00e1 qualificado nos Autos da A\u00e7\u00e3o&#8230;&#8230;, que move contra Beltrano de Tal (ou que lhe move Beltrano de Tal), em tr\u00e2mite perante esse R. Ju\u00edzo e Cart\u00f3rio do &#8230;.. Of\u00edcio (Proc. n. &#8230;..\/79), que, em cumprimento ao R. despacho de Vossa Excel\u00eancia exarado \u00e0s fls.  &#8230;&#8230;, vem sanar o defeito &#8230;&#8230;<\/p>\n<p>Esclarece mais que &#8230;&#8230; (se for o caso e se for cab\u00edvel).<\/p>\n<p>Termos em que<\/p>\n<p>P. E. Deferimento.<\/p>\n<p>Local e data.<\/p>\n<p><em>a<\/em>)\tAssinatura do advogado<\/p>\n<p>\tNome do advogado<\/p>\n<p>\tOAB &#8211; Se\u00e7\u00e3o de S\u00e3o Paulo n. &#8230;&#8230;..<\/p>\n<p>\tCIC n. &#8230;&#8230;..<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[510],"class_list":["post-19659","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-falencia-e-recuperacao"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/19659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=19659"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=19659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}