{"id":17791,"date":"2023-07-14T17:16:49","date_gmt":"2023-07-14T17:16:49","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-14T17:16:49","modified_gmt":"2023-07-14T17:16:49","slug":"quesitos-de-defesa-para-pericia-de-insanidade-mental","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/quesitos-de-defesa-para-pericia-de-insanidade-mental\/","title":{"rendered":"[MODELO] Quesitos de Defesa para Per\u00edcia de Insanidade Mental"},"content":{"rendered":"<p><strong>QUESITOS  DA  DEFESA  PARA  PER\u00cdCIA  DE  INSANIDADE  MENTAL<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>PR &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;<\/p>\n<p>Acusado &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>1.<\/strong> Ao tempo da a\u00e7\u00e3o imputada, era o(a) acusado(a) portador de <strong>doen\u00e7a<\/strong> <strong>mental<\/strong> ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>2.<\/strong> Em caso afirmativo, qual a doen\u00e7a mental e quais s\u00e3o os seus sintomas ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>3. <\/strong>Essa doen\u00e7a o(a) tornava <strong>inteiramente incapaz de entender<\/strong> o car\u00e1ter criminoso do fato cuja pr\u00e1tica lhe \u00e9 imputada ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>4. <\/strong>Se era capaz de entender o car\u00e1ter criminoso do fato, o(a) acusado(a) <strong>era inteiramente incapaz de determinar-se<\/strong> de acordo com esse entendimento ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>5. <\/strong>Se negativa a resposta ao 1<sup>o<\/sup> quesito, o(a) acusado(a) \u00e9 portador de <strong>desenvolvimento mental incompleto ou retardado<\/strong> ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>6. <\/strong>Em caso afirmativo, esse desenvolvimento mental incompleto, ou retardado, o(a) tornava<strong> inteiramente incapaz de entender<\/strong> o car\u00e1ter criminoso do fato ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>7. <\/strong>Se era capaz de entender o car\u00e1ter criminoso do fato, esse desenvolvimento mental incompleto, ou retardado, o tornava <strong>inteiramente incapaz de determinar-se<\/strong>  de acordo com esse entendimento ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>8. <\/strong>Em virtude desse desenvolvimento mental incompleto, ou retardado, o(a) acusado(a) era <strong>apenas parcialmente capaz de entender<\/strong> o car\u00e1ter criminoso do fato (par\u00e1grafo \u00fanico do art.26 do CP) ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>9. <\/strong>Se era capaz de entender o car\u00e1ter criminoso do fato, total ou parcialmente, era o(a) acusado(a), em virtude desse desenvolvimento mental incompleto, ou retardado, <strong>apenas parcialmente capaz de determinar-se<\/strong> de acordo com esse entendimento (par\u00e1grafo \u00fanico do art.26 do CP) ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>10. <\/strong>Se negativas as respostas ao primeiro e quinto quesitos, era o(a) acusado(a) portador de alguma <strong>perturba\u00e7\u00e3o da sa\u00fade mental<\/strong> ao tempo da a\u00e7\u00e3o imputada?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>11. <\/strong>Em virtude dessa perturba\u00e7\u00e3o da sa\u00fade mental, era o(a) acusado(a) apenas <strong>parcialmente capaz de entender<\/strong> o car\u00e1ter criminoso do fato (par\u00e1grafo \u00fanico do art.26 do CP) ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>12. <\/strong>Se era capaz de entender o car\u00e1ter criminoso do fato, total ou parcialmente, era o(a) acusado(a), em virtude dessa perturba\u00e7\u00e3o da sa\u00fade mental, apenas <strong>parcialmente capaz de determinar-se<\/strong> de acordo com esse entendimento (par\u00e1grafo \u00fanico do art.26 do CP) ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>13. <\/strong>O(a) acusado(a) era <strong>oligofr\u00eanico<\/strong> ao tempo do fato ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>14. <\/strong>\u00c0 vista do quadro sintomatol\u00f3gico que apresenta o(a) acusado(a), e das condi\u00e7\u00f5es em que teria desenvolvido-se a a\u00e7\u00e3o criminosa, poderia o(a) acusado(a) ter agido <strong>sob a influ\u00eancia de algum trauma psicol\u00f3gico, ou qualquer outra causa, que lhe causasse um moment\u00e2neo lapso de entendimento ou de determina\u00e7\u00e3o?<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>15. <\/strong>Qual <strong>o tratamento psiqui\u00e1trico aconselh\u00e1vel<\/strong> para o(a) acusado(a) ?<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Rio de Janeiro, &#8230;&#8230;&#8230;&#8230; de &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.. de &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.<strong>.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[534],"class_list":["post-17791","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-pericia-quesitos"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/17791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=17791"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=17791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}