{"id":14550,"date":"2023-07-14T14:43:48","date_gmt":"2023-07-14T14:43:48","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-14T14:43:48","modified_gmt":"2023-07-14T14:43:48","slug":"comunicado-de-nao-necessidade-de-novos-documentos-modelo-de-acao-declaratoria","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/comunicado-de-nao-necessidade-de-novos-documentos-modelo-de-acao-declaratoria\/","title":{"rendered":"[MODELO] Comunicado de n\u00e3o necessidade de novos documentos  &#8211;  Modelo de A\u00e7\u00e3o Declarat\u00f3ria"},"content":{"rendered":"<p>ESPECIFICA\u00c7\u00d5ES DE PROVAS \u2013 APRESENTA\u00c7\u00c3O DE N\u00c3O NECESSIDADE DE NOVOS DOCUMENTOS \u2013 MATERIAL CONSTANTE INICIAL &#8211; NOVO CPC<\/p>\n<p>EXCELENT\u00cdSSIMO(A) SENHOR(A) DOUTOR(A) JUIZ(A) FEDERAL DA &#8230;\u00aa VARA PREVIDENCI\u00c1RIA DA JUSTI\u00c7A FEDERAL DO TRF \u2013 &#8230;\u00aa REGI\u00c3O.<\/p>\n<p>Pular 10 linhas<\/p>\n<p>\u2006 \u2006 \u2006 \u2006 \u2006 &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.., j\u00e1 qualificado nos autos da A\u00c7\u00c3O DECLARAT\u00d3RIA C\/C PRECEITO CONDENAT\u00d3RIO, contra o INSS &#8211; INSTITUTO NACIONAL DO SEGURO SOCIAL, Processo<\/p>\n<p>n\u00ba &#8230;&#8230;&#8230;.., que tramita por este E. Ju\u00edzo, por seu procurador e advogado infra-assinado, vem perante V. Exa., em atendimento ao r. despacho exarado \u00e0s fls. Dos autos, comunicar que a Autora n\u00e3o pretende especificar provas, uma vez que esta j\u00e1 consta nos autos, informando que \u201ca\u2006 \u2006 mat\u00e9ria discutida nestes autos \u00e9 unicamente de direito, impondo-se com isso o julgamento antecipado da lide\u201d.<\/p>\n<p>Nestes termos,<\/p>\n<p>Pede deferimento.<\/p>\n<p>[Local] [data]<\/p>\n<p>__________________________________<\/p>\n<p>[Nome Advogado] &#8211; [OAB] [UF].<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[883],"class_list":["post-14550","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-previdenciario"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/14550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=14550"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=14550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}