{"id":12903,"date":"2023-07-14T13:35:11","date_gmt":"2023-07-14T13:35:11","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-14T13:35:11","modified_gmt":"2023-07-14T13:35:11","slug":"alternativa-de-nome-social-em-titulo-e-documentos","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/alternativa-de-nome-social-em-titulo-e-documentos\/","title":{"rendered":"[MODELO] ALTERNATIVA DE NOME SOCIAL EM T\u00cdTULO E DOCUMENTOS"},"content":{"rendered":"<p>EXMO. SR. DR. JUIZ DE DIREITO DO TRIBUNAL REGIONAL ELEITORAL DO &#8230;.. JU\u00cdZO DA &#8230;&#8230; ZONA ELEITORA DE &#8230;..<\/p>\n<p>AUTOS N\u00ba &#8230;..\/&#8230;..<br \/>REQUERENTE: JU\u00cdZO DA &#8230;&#8230; Z.E. DE &#8230;&#8230;&#8230;&#8230;..<br \/>REQUERIDO: &#8230;..<\/p>\n<p>&#8230;.., brasileiro (a), (estado civil), profissional da \u00e1rea de &#8230;.., portador (a) do CIRG n.\u00ba &#8230;.. e do CPF n.\u00ba &#8230;.., residente e domiciliado (a) na Rua &#8230;.., n.\u00ba &#8230;.., Bairro &#8230;.., Cidade &#8230;.., Estado &#8230;.., por interm\u00e9dio de seu (sua) advogado(a) e bastante procurador(a) (procura\u00e7\u00e3o em anexo &#8211; doc. 01), com escrit\u00f3rio profissional sito \u00e0 Rua &#8230;.., n\u00ba &#8230;.., Bairro &#8230;.., Cidade &#8230;.., Estado &#8230;.., onde recebe notifica\u00e7\u00f5es e intima\u00e7\u00f5es, vem mui respeitosamente \u00e0 presen\u00e7a de Vossa Excel\u00eancia apresentar;<\/p>\n<p>ALEGA\u00c7\u00d5ES FINAIS<\/p>\n<p>pelos motivos de fato e de direito a seguir aduzidos.<\/p>\n<p>DOS FATOS<\/p>\n<p>O Requerido, foi pelo ilustre escriv\u00e3o da &#8230;.. Zona Eleitoral descoberto que requereu sua inscri\u00e7\u00e3o naquela zona eleitoral em &#8230;.. de &#8230;&#8230;&#8230;.. de &#8230;.., com o nome feminino de &#8230;., constatando tamb\u00e9m a exist\u00eancia dos eleitores &#8230;&#8230;&#8230; e &#8230;&#8230;, com a mesma filia\u00e7\u00e3o e a mesma data de nascimento, divergindo apenas no local do nascimento, sendo aqueles eleitores cadastrados junto a &#8230;&#8230; de &#8230;&#8230;. em se\u00e7\u00f5es diversas de n\u00ba &#8230;.., o que foi tudo devidamente constatado atrav\u00e9s da farta documenta\u00e7\u00e3o anexada aos presentes autos;<\/p>\n<p>Que autuado o presente procedimento, o \u00ednclito Magistrado da Vara designou oitiva do Requerido para o dia &#8230;. de &#8230;. do corrente ano as &#8230;&#8230; horas, o qual foi ouvido e justificou a duplicidade de inscri\u00e7\u00e3o nas zonas eleitorais alegando o seguinte:<\/p>\n<p>&quot;Que em verdade seu nome \u00e9 &#8230;&#8230;&#8230;, do sexo masculino, tendo se apresentado como &#8230;&#8230;&#8230;&#8230;, n\u00e3o s\u00f3 para seu cadastramento eleitoral perante a esta zona, como tamb\u00e9m para a obten\u00e7\u00e3o da c\u00e9dula de identidade, j\u00e1 expedida pelo instituto de Identifica\u00e7\u00e3o do &#8230;&#8230;&#8230;&#8230;&#8230;, para evitar constrangimentos em estabelecimentos banc\u00e1rios, comerciais e reparti\u00e7\u00f5es p\u00fablica em geral, onde tivesse de apresentar seus documentos, em face de sua pessoa de apresentar como pessoa do sexo feminino;<br \/>Que para tanto fez uso de fotoc\u00f3pia de sua certid\u00e3o de Nascimento, encartada \u00e0s fls. 09, que foi adulterada por uma pessoa de sua confian\u00e7a, mas que n\u00e3o se recorda de seu nome, que alterou o sexo consignado naquele documento para feminino;<br \/>Que, a pessoa que providenciou as altera\u00e7\u00f5es partindo de uma fotoc\u00f3pia da certid\u00e3o original, trabalhava junto ao Cart\u00f3rio do Registro Civil de &#8230;&#8230;&#8230;&#8230;. de &#8230;&#8230;.. Que n\u00e3o tem irm\u00e3 g\u00eamea.<br \/>Quem al\u00e9m disso, o declarante obteve outra inscri\u00e7\u00e3o no cadastro eleitoral no Estado de &#8230;&#8230;&#8230;, com o nome &#8230;&#8230;&#8230;&#8230;&#8230;, mantendo-se a mesma filia\u00e7\u00e3o e data de nascimento, a partir de uma c\u00e9dula de identidade preenchida com informa\u00e7\u00f5es falsas, ou seja, sem registro oficial junto \u00e0 Secret\u00e1ria de Seguran\u00e7a Publica do Estado de &#8230;&#8230;&#8230;.., obteve gra\u00e7as a um funcion\u00e1rio de nome &#8230;&#8230;&#8230;., j\u00e1 falecido, que trabalhava naquele \u00f3rg\u00e3o.<br \/>Que, quando de sua inscri\u00e7\u00e3o como eleitor no Estado de &#8230;&#8230;&#8230;&#8230;.., usando o nome de &#8230;&#8230;&#8230;, foi consignado como seu Munic\u00edpio de &#8230;&#8230;&#8230;<br \/>Que, com o t\u00edtulo de eleitor usando o nome de &#8230;&#8230;.., votou uma ou duas vezes no Estado de &#8230;&#8230;&#8230;&#8230;&#8230;.. na Capital&quot;;<\/p>\n<p>Cultos e zelosas autoridades, verifica-se pelo depoimento singelo do Autuado, mesmo numa an\u00e1lise meramente perfunct\u00f3ria, ser ele uma verdadeira v\u00edtima do preconceito do ser humano para com aqueles que por for\u00e7a da natureza fogem aos padr\u00f5es que o homem criou, e tamb\u00e9m que a declarante como diz em suas pr\u00f3pria palavras somente tentou elaborar um documento com um nome feminino &quot;para evitar constrangimentos em estabelecimentos banc\u00e1rios, comerciais e reparti\u00e7\u00f5es p\u00fablicas em geral, onde tive de apresentar seus documentos, em face de sua op\u00e7\u00e3o pessoal de se apresentar como pessoa do sexo feminino&quot;;<\/p>\n<p>Observa-se da\u00ed, que o declarante n\u00e3o iria usar o t\u00edtulo que tentava fazer para fins escusos, se n\u00e3o pra escapar a discrimina\u00e7\u00e3o que sofria, e que inviabiliza a sua vida em sociedade, salientando-se, tamb\u00e9m que n\u00e3o trouxe nenhum preju\u00edzo ao estado e nem a qualquer pessoa, tudo n\u00e3o passando de uma mera tentativa;<\/p>\n<p>DO DIREITO<\/p>\n<p>Saliente-se por outro lado, que o declarante, \u00e9 uma pessoa que se esfor\u00e7a em viver dentro da sociedade, trabalha, mant\u00e9m \u00f3timas rela\u00e7\u00f5es com a sua fam\u00edlia e a sociedade, possui domicilio fixo, e luta por todos os meios para n\u00e3o cair na mesmice de sempre como outras pessoas que desgra\u00e7adamente nasceram, com a apar\u00eancia f\u00edsica de um sexo, mas possuem a cabe\u00e7a de outro, sabendo-se, que a maiorias desses infelizes descambam para a prostitui\u00e7\u00e3o, pois dificilmente encontram lugar na sociedade para viver como suas cabe\u00e7as determinam e n\u00e3o como o seu corpo f\u00edsico demonstra. Lembre-se, que o declarante apresentou-se perante Vossas Excel\u00eancias, demonstrando humildade, respeito e sobretudo transpar\u00eancia, pois nada negou sobre sua qualifica\u00e7\u00e3o ou sobre a maneira incorreta porque tentou escapar do preconceito advindo da sociedade que o impedia at\u00e9 de trabalhar e sobreviver.<\/p>\n<p>A discrimina\u00e7\u00e3o \u00e9 um ato anti-constitucional, devendo o requerido ser respeitado pelo que \u00e9, homem ou mulher, branco ou negro, rico ou pobre, pois todos somos pessoas e merecemos ser aceitos pelo nosso interior e n\u00e3o pelo que o nosso exterior mostra.<\/p>\n<p>DOS PEDIDOS<\/p>\n<p>Isto posto, e com o mais que ser\u00e1 suprido por V.Exas, autoridades cultas, competentes e experientes, o Requerido, apela para o not\u00f3rio esp\u00edrito humanista das autoridades brasileiras, no sentido de ser lhe dada uma oportunidade, j\u00e1 que n\u00e3o causou preju\u00edzo a quem quer que seja e que agiu erroneamente em decorr\u00eancia de legitimo ato de legitima defesa do direito de levar uma vida normal dentro da sociedade.<\/p>\n<p>Nesses Termos,<br \/>Pede Deferimento.<\/p>\n<p>[Local], [dia] de [m\u00eas] de [ano].<\/p>\n<p>[Assinatura do Advogado]<br \/>[N\u00famero de Inscri\u00e7\u00e3o na OAB]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[519],"class_list":["post-12903","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-eleitorais"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/12903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=12903"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=12903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}