{"id":12726,"date":"2023-07-14T13:25:43","date_gmt":"2023-07-14T13:25:43","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-14T13:25:43","modified_gmt":"2023-07-14T13:25:43","slug":"acao-de-rescisao-de-contrato-de-venda-a-credito-com-reserva-de-dominio","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/acao-de-rescisao-de-contrato-de-venda-a-credito-com-reserva-de-dominio\/","title":{"rendered":"[MODELO] A\u00e7\u00e3o de Rescis\u00e3o de Contrato de Venda a Cr\u00e9dito com Reserva de Dom\u00ednio"},"content":{"rendered":"<p><a href=\"Tabelaco.doc\">Voltar<\/a><\/p>\n<p><strong>EXMO. SR. DR. JUIZ DE DIREITO DA &#8230;. \u00aa VARA C\u00cdVEL DA COMARCA DE &#8230;.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. (qualifica\u00e7\u00e3o), pessoa jur\u00eddica de direito privado, com sede na Rua &#8230;. n\u00ba &#8230;., na Cidade de &#8230;., Estado &#8230; &#8230;., devidamente inscrita no CGC\/MF sob o n\u00ba &#8230;., por seu advogado infra-assinado (procura\u00e7\u00e3o em anexo), devidamente inscrito na OAB\/Se\u00e7\u00e3o do &#8230;., sob o n\u00ba &#8230;., com escrit\u00f3rio profissional na Rua &#8230;. n\u00ba &#8230;., na Cidade de &#8230;., Estado .. &#8230;., vem, mui respeitosamente, perante Vossa Excel\u00eancia, propor a presente<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>A\u00c7\u00c3O DE RESCIS\u00c3O DE CONTRATO DE VENDA A CR\u00c9DITO COM RESERVA DE DOM\u00cdNIO<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>contra &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. (qualifica\u00e7\u00e3o), portador da C\u00e9dula de Identidade\/RG n\u00ba &#8230;., residente e domiciliado na Rua &#8230;. n\u00ba &#8230;., na Cidade de &#8230;., Estado . &#8230;., com fundamento nos arts. 1070 e seguintes do C\u00f3digo de Processo Civil, pelos motivos de fato e de direito a seguir aduzidos.<\/p>\n<p>\u00a0<\/p>\n<p>A Requerente vendeu ao Requerido, com reserva de dom\u00ednio, os bens m\u00f3veis abaixo descritos e relacionados na nota fiscal anexa, na conformidade do contrato de compra e venda com reserva de dom\u00ednio incluso, o qual se encontra devidamente formalizado e registrado em T\u00edtulos e Documentos:<\/p>\n<p>\u00a0<\/p>\n<p>.<\/p>\n<p>\u00a0<\/p>\n<p>A venda foi realizada pela import\u00e2ncia de R$ &#8230;&#8230;., pag\u00e1veis da seguinte forma: uma parcela \u00e0 vista, no valor de R$ &#8230;. e mais duas presta\u00e7\u00f5es, mensais, iguais e sucessivas, no valor de R$ &#8230;., cada uma, representadas pelas duplicatas de fatura n\u00bas &#8230;. e &#8230;., com vencimentos em &#8230;\/&#8230;\/&#8230; e &#8230;\/&#8230;\/&#8230;, respectivamente, assumindo o requerido o encargo de fiel deposit\u00e1rio das mercadorias, na forma da cl\u00e1usula &#8230;.\u00aa do referido instrumento.<\/p>\n<p>\u00a0<\/p>\n<p>Ocorre que o Requerido n\u00e3o cumpriu com as obriga\u00e7\u00f5es estipuladas no supra mencionado contrato, deixando de pagar as duplicatas vencidas, n\u00bas &#8230;. e &#8230;., com vencimentos em &#8230;\/&#8230;\/&#8230; e &#8230;.\/&#8230;\/&#8230;, respectivamente, no total de R$ &#8230;., motivo porque os t\u00edtulos forma levados a protesto, que se efetivou, conforme se v\u00eaem dos instrumentos anexos.<\/p>\n<p>\u00a0<\/p>\n<p>As partes elegeram o foro desta Comarca, com ren\u00fancia a qualquer outro, por mais privilegiado que fosse, para dirimir as quest\u00f5es oriundas do contrato.<\/p>\n<p>\u00a0<\/p>\n<p>Como se v\u00ea do contrato incluso, tal venda foi realizada mediante cl\u00e1usula de reserva de dom\u00ednio em favor da vendedora, ora Requerente; assim, com a juntada das duplicatas de fatura, vencidas, protestadas e n\u00e3o pagas, nos precisos termos do art. 1071 do C\u00f3digo de Processo Civil, requer a Vossa Excel\u00eancia digne-se determinar:<\/p>\n<p>\u00a0<\/p>\n<p>A) &quot;Audiatur et altera pars&quot;, apreender os bens m\u00f3veis r. descritos, para serem judicialmente depositados, oferecendo-se a pr\u00f3pria Requerente para proceder a remo\u00e7\u00e3o e dep\u00f3sito, sob as penas da Lei, \u00e0 vista de possuir condu\u00e7\u00e3o pr\u00f3pria e local adequado para o dep\u00f3sito, se assim permitir Vossa Excel\u00eancia;<\/p>\n<p>\u00a0<\/p>\n<p>B) Efetivada a apreens\u00e3o, requer a cita\u00e7\u00e3o do Requerido, para apresentar sua defesa, requerendo, e por interm\u00e9dio de perito eleito por Vossa Excel\u00eancia, se proceda a vistoria e valoriza\u00e7\u00e3o dos bens, levando-se em conta o pre\u00e7o de venda e a sua desvaloriza\u00e7\u00e3o pelo uso;<\/p>\n<p>\u00a0<\/p>\n<p>C) Cumpridas as demais formalidades de praxe, requer seja julgada procedente a presente a\u00e7\u00e3o, para o fim de ser a requerente reintegrada definitivamente na posse dos bens apreendidos, bem como, requer a condena\u00e7\u00e3o do requerido no pagamento do saldo devedor que for apurado, custas processuais, juros de mora de 1% a.m., corre\u00e7\u00e3o monet\u00e1ria, honor\u00e1rios advocat\u00edcios, despesas com protesto no valor de R$ &#8230;. e outras despesas que se registrarem, inclusive as de remo\u00e7\u00e3o.<\/p>\n<p>\u00a0<\/p>\n<p>Protesta provar o alegado por todos os meios em direito admitidos, bem como requer desde j\u00e1 os benef\u00edcios do \u00a7 2\u00ba do art. 172 do C\u00f3digo de Processo Civil.<\/p>\n<p>\u00a0<\/p>\n<p>D\u00e1-se \u00e0 causa o valor de R$ &#8230;.<\/p>\n<p>\u00a0<\/p>\n<p>Nestes Termos, <\/p>\n<p>Pede Deferimento.<\/p>\n<p>\u00a0<\/p>\n<p>&#8230;., &#8230;. de &#8230;. de &#8230;.<\/p>\n<p>\u00a0<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;<\/p>\n<p>Advogado OAB\/&#8230;.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[516],"class_list":["post-12726","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-empresarial-e-societario"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/12726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=12726"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=12726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}