{"id":11984,"date":"2023-07-14T11:34:55","date_gmt":"2023-07-14T11:34:55","guid":{"rendered":"https:\/\/easyjur.com\/blog\/?post_type=modelos-de-peticao&#038;p=3650"},"modified":"2023-07-14T11:34:55","modified_gmt":"2023-07-14T11:34:55","slug":"execucao-obrigacoes-alternativas-cumprimento-sentenca","status":"publish","type":"modelos-de-peticao","link":"https:\/\/easyjur.com\/blog\/modelos-de-peticao\/execucao-obrigacoes-alternativas-cumprimento-sentenca\/","title":{"rendered":"[MODELO] Execu\u00e7\u00e3o Obriga\u00e7\u00f5es Alternativas  &#8211;  Cumprimento Senten\u00e7a"},"content":{"rendered":"<p>EXECU\u00c7\u00c3O DAS OBRIGA\u00c7\u00d5ES ALTERNATIVAS &#8211; NOVO CPC<\/p>\n<p>EXMO. SR. DR. JUIZ DE DIREITO DA ____________ DA COMARCA DE __________________ &#8211; ___<\/p>\n<p>Pular 10 linhas<\/p>\n<p>__________, brasileiro, solteiro, professor, CPF n\u00ba ___-___-___-__, RG n\u00ba __________, nascido em __\/__\/__, filia\u00e7\u00e3o __________ e __________, residente na Rua __________, n\u00ba ___, Bairro ___________, nesta cidade, vem, por meio de seu advogado, que receber\u00e1 as notifica\u00e7\u00f5es e intima\u00e7\u00f5es na Rua __________, n\u00ba ___, Bairro __________, nesta cidade (doc. 1), perante Vossa Excel\u00eancia, com fulcro no art. 800 do CPC\/2015, promover a presente EXECU\u00c7\u00c3O DE OBRIGA\u00c7\u00d5ES ALTERNATIVAS, contra __________, brasileiro, solteiro, m\u00e9dico, CPF n\u00ba ___-___-___-__, RG n\u00ba __________, nascido em __\/__\/__, filia\u00e7\u00e3o __________ e __________, residente na Rua __________, n\u00ba ___, Bairro ___________, nesta cidade, pelos fatos que passa a expor:<\/p>\n<p>A r. senten\u00e7a de fls. __, proferida no processo n\u00ba ___________, condenou o Executado a entregar ao Exequente o im\u00f3vel ___________ (descrever o bem), ou a pagar-lhe a quantia de R$ _______,__ (__________ reais). (docs. 2 a 5)<\/p>\n<p>Entretanto, o Executado n\u00e3o conseguiu receber amigavelmente nem o im\u00f3vel, nem o dinheiro.<\/p>\n<p>ANTE O EXPOSTO, requer-se a cita\u00e7\u00e3o do Executado para que cumpra a senten\u00e7a j\u00e1 referida no prazo de 10 (dez) dias, sob pena de caber ao Exequente o direito de escolha.<\/p>\n<p>Requer ainda, que o Executado responda pelo \u00f4nus da sucumb\u00eancia.<\/p>\n<p>Almeja-se provar o alegado por todos os meios admitidos pelo direito.<\/p>\n<p>Atribui-se \u00e0 causa o valor de R$ ______,__ (___________ reais).<\/p>\n<p>Nestes termos,<\/p>\n<p>Pede deferimento.<\/p>\n<p>[Local] [data]<\/p>\n<p>__________________________________<\/p>\n<p>[Nome Advogado] &#8211; [OAB] [UF].<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"content-type":""},"categoria-modelo":[525],"class_list":["post-11984","modelos-de-peticao","type-modelos-de-peticao","status-publish","hentry","categoria-modelo-civil"],"_links":{"self":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao\/11984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/modelos-de-peticao"}],"about":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/types\/modelos-de-peticao"}],"wp:attachment":[{"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/media?parent=11984"}],"wp:term":[{"taxonomy":"categoria-modelo","embeddable":true,"href":"https:\/\/easyjur.com\/blog\/wp-json\/wp\/v2\/categoria-modelo?post=11984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}